{"id":17063,"date":"2026-02-23T12:28:50","date_gmt":"2026-02-23T11:28:50","guid":{"rendered":"https:\/\/www.ellab.com\/validazione-dellumidita\/"},"modified":"2026-03-25T15:56:25","modified_gmt":"2026-03-25T14:56:25","slug":"convalida-dellumidita","status":"publish","type":"page","link":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/","title":{"rendered":"Validazione dell&#8217;umidit\u00e0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"17063\" class=\"elementor elementor-17063 elementor-8863\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b68b90 e-con-full e-flex e-con e-parent\" data-id=\"8b68b90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7fe102 elementor-widget elementor-widget-hero_ellab\" data-id=\"f7fe102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hero_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-hero-f7fe102\" class=\"d-flex align-items-center px-3 px-md-0 \" style=\"min-height: 100vh;\">\r\n    <div class=\"container\">\r\n        <div class=\"row justify-content-start\">\r\n\r\n            \r\n            <div class=\"col-12 col-md-12\">\r\n\r\n\r\n                \r\n                \r\n                                    <h1 class=\"custom-title fs-56 fw-semibold mb-5 text-secondary\">\r\n                        <span class=\"text-secondary\">Validazione affidabile dell'umidit\u00e0 relativa per ambienti regolamentati<\/span>                    <\/h1>\r\n                \r\n                \r\n                                    <h6 class=\"hero-subtitle fs-24 fw-semibold mb-4 text-white w-100 w-md-100\">\r\n                        Misurazioni dell&#039;umidit\u00e0 relativa ad alta precisione, apparecchiature affidabili e conformit\u00e0 garantita.                    <\/h6>\r\n                \r\n                                    <p class=\"fs-24 fw-light mb-4 text-white w-100 w-md-75\">\r\n                        Dalle camere di stabilit\u00e0 alle celle ambientali e agli spazi di laboratorio controllati, i sistemi di validazione dell&#039;umidit\u00e0 di Ellab forniscono dati precisi e tracciabili sull&#039;umidit\u00e0 relativa in un ampio intervallo di misurazione. I nostri data logger di umidit\u00e0, i sensori di umidit\u00e0 relativa e il software semplificano le qualifiche e riducono i tempi di inattivit\u00e0 grazie a risultati accurati e ripetibili.                     <\/p>\r\n                \r\n                                                        <a href=\"#popmake-7957\"\r\n                        class=\"btn btn-sm mt-4 btn-light\"\r\n                        >\r\n                        Richiedi una demo gratuita                    <\/a>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n<style>\r\n    #ellab-hero-f7fe102 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/humidity_validation_01.jpg');\r\n        background-size: cover;\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        #ellab-hero-f7fe102 {\r\n            background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/humidity_validation_01.jpg');\r\n            background-position: center center;\r\n        }\r\n    }\r\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d2dd4da e-con-full e-flex e-con e-parent\" data-id=\"d2dd4da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-626be23 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"626be23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-626be23\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 \">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-primary \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-5 text-primary\">\r\n                        <span class=\"text-primary\">Dati sull'umidit\u00e0 affidabili, anche in <span class=\"text-secondary\">ambienti difficili<\/span><\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-primary\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                                    <div class=\"fs-18 fw-light mb-5 text-primary lh-base wysiwyg-list\">\r\n                        <p>L'umidit\u00e0 relativa gioca un ruolo cruciale nella stabilit\u00e0 del prodotto, nel controllo microbico e nella coerenza ambientale. Tuttavia, la validazione dell'umidit\u00e0 relativa presenta spesso sfide come la deriva dei sensori, tempi di risposta lenti, effetti della condensa o apparecchiature che non riescono a mantenere l'accuratezza nell'intero intervallo di umidit\u00e0. <\/p>\n<p>I sistemi di validazione dell'umidit\u00e0 di Ellab sono progettati per risolvere questi problemi. Con sensori di umidit\u00e0 relativa resistenti e <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/datalogger-senza-fili\/\">data logger<\/a> di temperatura\/umidit\u00e0 relativa ad alta precisione, otterrai dati stabili e ripetibili e una tracciabilit\u00e0 completa in una variet\u00e0 di ambienti controllati. Ci\u00f2 riduce le ripetizioni dei test, elimina l'incertezza e aiuta a garantire la piena conformit\u00e0 alle aspettative normative globali.  <\/p>\n                    <\/div>\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                \r\n                <!-- Paragraph 2 -->\r\n                \r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                \r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-626be23 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/humidity_validation_02b.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: bottom left;\r\n        background-size: 27% auto;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-626be23 {\r\n            background-position: bottom left;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-626be23 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-626be23');\r\n        const content = document.getElementById('readmore-content-626be23');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07c9826 e-con-full e-flex e-con e-parent\" data-id=\"07c9826\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4933e80 elementor-widget elementor-widget-one_column_with_grid_ellab\" data-id=\"4933e80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"one_column_with_grid_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\r\n<section id=\"ellab-one-column-4933e80\"\r\n    class=\"py-4 py-lg-5 \">\r\n\r\n    <div class=\"container my-4 my-lg-5 \">\r\n        <div class=\"row text-center justify-content-center\">\r\n\r\n            \r\n            \r\n            \r\n                        \r\n                            <!-- Subtitle Top -->\r\n                                    <div class=\"col-12 mt-5\">\r\n                        <h5 class=\"fs-36 fw-semibold text-primary mb-5\">\r\n                            Per cosa pu\u00f2 essere utilizzato un sistema di validazione dell'umidit\u00e0 relativa?                        <\/h5>\r\n                    <\/div>\r\n                \r\n\r\n                <!-- ==================== Grid Applications ==================== -->\r\n                <div class=\"col-12 col-md-10\">\r\n                                        <div class=\"row row-cols-2 row-cols-sm-2 row-cols-lg-4 gx-4 gy-0 g-md-5 justify-content-center\">\r\n                                                    <div class=\"col d-flex justify-content-center\">\r\n                                <div class=\"align-items-center text-center\">\r\n                                    \r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/applications-1.jpg\"\r\n                                                alt=\"Apparecchiature di stoccaggio e laboratorio\"\r\n                                                class=\"img-fluid mb-3 rounded-circle\"\r\n                                                style=\"max-width: 140px; width: 140px; height: 140px; object-fit: cover;\" \/>\r\n                                        \r\n                                                                                    <h6 class=\"fs-20 fw-semibold mb-2 text-primary\">Apparecchiature di stoccaggio e laboratorio<\/h6>\r\n                                        \r\n                                                                                    <h6 class=\"fs-18 fw-light mb-2 text-primary\">Mappatura dell&#039;umidit\u00e0 in stanze, magazzini, centri di distribuzione, incubatori e spazi di laboratorio controllati.<\/h6>\r\n                                        \r\n                                                                        <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col d-flex justify-content-center\">\r\n                                <div class=\"align-items-center text-center\">\r\n                                    \r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-stability-chamber.png\"\r\n                                                alt=\"Camere ambientali\"\r\n                                                class=\"img-fluid mb-3 rounded-circle\"\r\n                                                style=\"max-width: 140px; width: 140px; height: 140px; object-fit: cover;\" \/>\r\n                                        \r\n                                                                                    <h6 class=\"fs-20 fw-semibold mb-2 text-primary\">Camere ambientali<\/h6>\r\n                                        \r\n                                                                                    <h6 class=\"fs-18 fw-light mb-2 text-primary\">Validazione di camere di stabilit\u00e0, celle ambientali e configurazioni per test climatici.<\/h6>\r\n                                        \r\n                                                                        <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col d-flex justify-content-center\">\r\n                                <div class=\"align-items-center text-center\">\r\n                                    \r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-chemical-sterilization-eto.png\"\r\n                                                alt=\"Sterilizzazione e decontaminazione\"\r\n                                                class=\"img-fluid mb-3 rounded-circle\"\r\n                                                style=\"max-width: 140px; width: 140px; height: 140px; object-fit: cover;\" \/>\r\n                                        \r\n                                                                                    <h6 class=\"fs-20 fw-semibold mb-2 text-primary\">Sterilizzazione e decontaminazione<\/h6>\r\n                                        \r\n                                                                                    <h6 class=\"fs-18 fw-light mb-2 text-primary\">Supporto ai flussi di lavoro di validazione in cui l&#039;umidit\u00e0 influisce sul controllo microbico.<\/h6>\r\n                                        \r\n                                                                        <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col d-flex justify-content-center\">\r\n                                <div class=\"align-items-center text-center\">\r\n                                    \r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-lab.png\"\r\n                                                alt=\"Apparecchiature di produzione e di processo\"\r\n                                                class=\"img-fluid mb-3 rounded-circle\"\r\n                                                style=\"max-width: 140px; width: 140px; height: 140px; object-fit: cover;\" \/>\r\n                                        \r\n                                                                                    <h6 class=\"fs-20 fw-semibold mb-2 text-primary\">Apparecchiature di produzione e di processo<\/h6>\r\n                                        \r\n                                                                                    <h6 class=\"fs-18 fw-light mb-2 text-primary\">Garanzia di condizioni di umidit\u00e0 relativa conformi nelle aree di produzione sensibili all&#039;umidit\u00e0.<\/h6>\r\n                                        \r\n                                                                        <\/div>\r\n                            <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n\r\n                <!-- Subtitle Bottom -->\r\n                \r\n            \r\n\r\n            <!-- ==================== Button All Applications ==================== -->\r\n            \r\n            <!-- ==================== Video ==================== -->\r\n\r\n            \r\n            \r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n<style>\r\n    #ellab-one-column-4933e80 {\r\n        background-image: url('');\r\n        background-size: auto;\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n    }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-one-column-4933e80 {\r\n            background-position: center center;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f66091 e-con-full e-flex e-con e-parent\" data-id=\"2f66091\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa11ded elementor-widget elementor-widget-two_columns_ellab\" data-id=\"fa11ded\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-fa11ded\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 bg-success\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-5 mb-5 text-white\">\r\n                        <span class=\"text-white\">Scopri come una validazione accurata dell'umidit\u00e0 relativa pu\u00f2 migliorare i tuoi studi<\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                                    <h6 class=\"fs-24 fw-semibold mb-4 text-white\">\r\n                        Scopri come gli strumenti di validazione dell&#039;umidit\u00e0 di Ellab riducono i tempi di studio, migliorano l&#039;accuratezza e supportano flussi di lavoro di validazione pienamente conformi, indipendentemente dalla complessit\u00e0 dell&#039;ambiente.                    <\/h6>\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                \r\n                <!-- Paragraph 2 -->\r\n                \r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                <iframe class=\"pardotform\" src=\"https:\/\/www2.ellab.com\/l\/971953\/2022-08-30\/9hwy\" width=\"100%\" height=\"680\" frameborder=\"0\" pardot-form-name=\"IT-Contact-Ellab\"><\/iframe>\r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-fa11ded {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/img_form_module-2.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n        background-size: cover;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-fa11ded {\r\n            background-position: center center;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-fa11ded .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-fa11ded');\r\n        const content = document.getElementById('readmore-content-fa11ded');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54530fb e-con-full e-flex e-con e-parent\" data-id=\"54530fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89acab8 elementor-widget elementor-widget-testimonial_ellab\" data-id=\"89acab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-testimonial-89acab8\" class=\"section-carousel testimonial-carousel py-4 py-lg-5 px-3 px-md-0\" aria-label=\"Testimonials Carousel\">\r\n    <div class=\"container my-4 my-lg-5\">\r\n        <div class=\"row justify-content-center\">\r\n            <div class=\"col-12 col-md-10 mx-auto\">\r\n                <div class=\"row justify-content-center\">\r\n                    <div class=\"col-12\">\r\n\r\n                        \r\n                                                    <h3 class=\"custom-title fs-36 fw-semibold mb-5 text-center text-primary\">\r\n                                <span class=\"text-primary\"><\/span>                            <\/h3>\r\n                        \r\n\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                                    <div class=\"splide\" id=\"testimonial-splide-89acab8\">\r\n                        <div class=\"splide__track\">\r\n                            <ul class=\"splide__list\">\r\n                                                                    <li class=\"splide__slide\">\r\n                                        <div class=\"bg-gradient-light p-5 rounded-4\">\r\n                                            <div class=\"row align-items-start\">\r\n                                                <div class=\"col-auto col-md-1 d-flex justify-content-center justify-content-md-start\">\r\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/quote.svg\"\r\n                                                            alt=\"Quote Mark\"\r\n                                                            class=\"quote-mark\" \/>\r\n                                                                                                    <\/div>\r\n                                                <div class=\"col-12 col-md-11\">\r\n                                                    <blockquote class=\"flex-grow-1 ms-0 ms-md-5 mb-0 mb-md-4\">\r\n                                                        <div class=\"fs-20 fst-italic mb-5 text-start\">\r\n                                                            <p><span class=\"TextRun SCXW122769311 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW122769311 BCX0\">Le migliori soluzioni di validazione per le apparecchiature farmaceutiche e biotecnologiche.<\/span><\/span><\/p>\n                                                        <\/div>\r\n                                                    <\/blockquote>\r\n                                                <\/div>\r\n                                                <footer class=\"text-center py-md-4 py-4\">\r\n                                                    <div class=\"fs-15 text-dark fw-bold\">Lukasz Kapron<\/div>\r\n                                                    <div class=\"fs-15 text-secondary fw-bold\">Polpharma Biologics<\/div>\r\n                                                    <div class=\"fs-13 text-muted fw-bold\"><\/div>\r\n                                                    <div class=\"fs-13 text-muted\"><\/div>\r\n                                                <\/footer>\r\n                                            <\/div>\r\n\r\n                                        <\/div>\r\n                                    <\/li>\r\n                                                                    <li class=\"splide__slide\">\r\n                                        <div class=\"bg-gradient-light p-5 rounded-4\">\r\n                                            <div class=\"row align-items-start\">\r\n                                                <div class=\"col-auto col-md-1 d-flex justify-content-center justify-content-md-start\">\r\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/quote.svg\"\r\n                                                            alt=\"Quote Mark\"\r\n                                                            class=\"quote-mark\" \/>\r\n                                                                                                    <\/div>\r\n                                                <div class=\"col-12 col-md-11\">\r\n                                                    <blockquote class=\"flex-grow-1 ms-0 ms-md-5 mb-0 mb-md-4\">\r\n                                                        <div class=\"fs-20 fst-italic mb-5 text-start\">\r\n                                                            <p>Ottimo servizio clienti e un prodotto eccellente. I sensori Ellab sono andati oltre le aspettative, ma nel corso degli anni, non importa quanto sia buono un prodotto, deve sapersi adattare. Il team di Ellab ci ascolta riguardo ai cambiamenti che potrebbero aiutarci o alla direzione che sta prendendo il nostro settore, adattando il prodotto per soddisfare le nostre esigenze. Rimangono all'avanguardia nel progresso ed \u00e8 per questo che continuiamo a sceglierli.   <\/p>\n                                                        <\/div>\r\n                                                    <\/blockquote>\r\n                                                <\/div>\r\n                                                <footer class=\"text-center py-md-4 py-4\">\r\n                                                    <div class=\"fs-15 text-dark fw-bold\">Jaret May<\/div>\r\n                                                    <div class=\"fs-15 text-secondary fw-bold\">Catalent<\/div>\r\n                                                    <div class=\"fs-13 text-muted fw-bold\"><\/div>\r\n                                                    <div class=\"fs-13 text-muted\"><\/div>\r\n                                                <\/footer>\r\n                                            <\/div>\r\n\r\n                                        <\/div>\r\n                                    <\/li>\r\n                                                                    <li class=\"splide__slide\">\r\n                                        <div class=\"bg-gradient-light p-5 rounded-4\">\r\n                                            <div class=\"row align-items-start\">\r\n                                                <div class=\"col-auto col-md-1 d-flex justify-content-center justify-content-md-start\">\r\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/quote.svg\"\r\n                                                            alt=\"Quote Mark\"\r\n                                                            class=\"quote-mark\" \/>\r\n                                                                                                    <\/div>\r\n                                                <div class=\"col-12 col-md-11\">\r\n                                                    <blockquote class=\"flex-grow-1 ms-0 ms-md-5 mb-0 mb-md-4\">\r\n                                                        <div class=\"fs-20 fst-italic mb-5 text-start\">\r\n                                                            <p><span class=\"TextRun SCXW12087468 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW12087468 BCX0\">La nostra struttura utilizza i data logger Ellab da anni. Abbiamo circa 200 unit\u00e0 e siamo molto soddisfatti. I rappresentanti di zona sono fantastici e sempre pronti ad aiutare. Un ottimo prodotto su cui investire. Inoltre, \u00e8 conforme alla normativa Part 11!    <\/span><\/span><\/p>\n                                                        <\/div>\r\n                                                    <\/blockquote>\r\n                                                <\/div>\r\n                                                <footer class=\"text-center py-md-4 py-4\">\r\n                                                    <div class=\"fs-15 text-dark fw-bold\">Don Narron<\/div>\r\n                                                    <div class=\"fs-15 text-secondary fw-bold\">GSK<\/div>\r\n                                                    <div class=\"fs-13 text-muted fw-bold\"><\/div>\r\n                                                    <div class=\"fs-13 text-muted\"><\/div>\r\n                                                <\/footer>\r\n                                            <\/div>\r\n\r\n                                        <\/div>\r\n                                    <\/li>\r\n                                                            <\/ul>\r\n                        <\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n\r\n<style>\r\n    #ellab-testimonial-89acab8 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/home_img_bg_6.png');\r\n        background-size: auto;\r\n        background-repeat: no-repeat;\r\n        background-position: center left;\r\n    }\r\n\r\n    @media (max-width: 991px) {\r\n        #ellab-testimonial-89acab8 {\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    #testimonial-splide-89acab8 .splide__pagination__page {\r\n        background: #d3d3d3 !important;\r\n        border: none !important;\r\n        opacity: 1 !important;\r\n        width: 6px !important;\r\n        height: 6px !important;\r\n        margin: 0 6px !important;\r\n    }\r\n\r\n    #testimonial-splide-89acab8 .splide__pagination__page.is-active {\r\n        background: var(--bs-primary) !important;\r\n        transform: scale(1.8) !important;\r\n    }\r\n\r\n    #testimonial-splide-89acab8 .bg-gradient-light {\r\n        background: linear-gradient(to right,\r\n                rgba(241, 242, 244, 0.6) 0%,\r\n                rgba(241, 242, 244, 0.85) 40%);\r\n    }\r\n\r\n\r\n    .elementor .quote-mark {\r\n        width: 200px;\r\n        max-width: none;\r\n        height: auto;\r\n        margin-bottom: 0;\r\n        \/* o lo que necesites *\/\r\n    }\r\n\r\n    @media (max-width: 1024px) {\r\n        .elementor .quote-mark {\r\n            width: 120px;\r\n            margin-bottom: 30px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767.98px) {\r\n        .elementor .quote-mark {\r\n            width: 60px;\r\n            margin-bottom: 30px;\r\n        }\r\n    }\r\n<\/style>\r\n\r\n\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        if (typeof Splide !== 'undefined') {\r\n            new Splide('#testimonial-splide-89acab8', {\r\n                type: 'loop',\r\n                perPage: 1,\r\n                arrows: false,\r\n                pagination: true,\r\n                autoplay: true,\r\n                interval: 5000,\r\n                pauseOnHover: true,\r\n                classes: {\r\n                    pagination: 'splide__pagination mt-4 text-center',\r\n                    page: 'splide__pagination__page',\r\n                },\r\n            }).mount();\r\n        }\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2aa3b7b e-con-full e-flex e-con e-parent\" data-id=\"2aa3b7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f688a6 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"8f688a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-8f688a6\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 bg-primary\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-5 mb-5 text-white\">\r\n                        <span class=\"text-white\"><span class=\"text-secondary\">Hardware<\/span> progettato per una validazione dell'umidit\u00e0 pronta per le ispezioni normative<\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                                    <div class=\"fs-18 fw-light mb-5 text-white lh-base wysiwyg-list\">\r\n                        <p>Gli strumenti di validazione dell'umidit\u00e0 di Ellab soddisfano le aspettative di FDA, ICH e MHRA fornendo misurazioni affidabili e pronte per gli audit per ogni qualifica.<\/p>\n<p>Tutte le apparecchiature sono progettate per prestazioni costanti e una tracciabilit\u00e0 completa durante ogni studio.<\/p>\n                    <\/div>\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                                                        <h6 class=\"fs-36 fw-semibold mt-5 mb-4 text-white\">\r\n                        Progettato per accuratezza, integrit\u00e0 ed efficienza                    <\/h6>\r\n                \r\n                <!-- Paragraph 2 -->\r\n                                    <span class=\"fs-18 fs-light mb-5 text-white lh-base\"><p><span class=\"TextRun SCXW207352247 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW207352247 BCX0\">Grazie alla rilevazione stabile dell'<\/span><span class=\"NormalTextRun SCXW207352247 BCX0\">umidit\u00e0 relativa<\/span><span class=\"NormalTextRun SCXW207352247 BCX0\">, <\/span><span class=\"NormalTextRun SCXW207352247 BCX0\">a componenti di lunga durata e a flussi di lavoro dei dati ottimizzati, i <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/\">sistemi di Ellab<\/a> aiutano a ridurre i tempi di inattivit\u00e0 e a minimizzare il rischio di <\/span><span class=\"NormalTextRun SCXW207352247 BCX0\">ripetizioni dei test<\/span><span class=\"NormalTextRun SCXW207352247 BCX0\">. I dati vengono acquisiti in modo sicuro e trasformati facilmente in report pronti per le ispezioni.<\/span><\/span><span class=\"EOP SCXW207352247 BCX0\" data-ccp-props=\"{}\"> <\/span><\/p>\n<p><strong><span class=\"TextRun SCXW260671700 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW260671700 BCX0\">Specifiche chiave:<\/span><\/span><\/strong><\/p>\n<\/span>\r\n                \r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                                    <div class=\"row g-4 \">\r\n                                            <\/div>\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                                    <div class=\"row pt-5\">\r\n                        <div class=\"col-12\">\r\n                            <div class=\"container bg-blur-primary rounded-4 p-4 p-md-5\">\r\n                                <ul class=\"list-unstyled\">\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Sensori di umidit\u00e0 relativa e data logger di umidit\u00e0 relativa ad alta precisione                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Opzioni di misurazione combinata di temperatura e umidit\u00e0                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Equilibrazione rapida per letture stabili dell&#039;umidit\u00e0 relativa                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Intervallo di misurazione dell&#039;umidit\u00e0 relativa fino al 100%                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Supporto per la calibrazione tracciabile                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Progettato per la validazione conforme alle GMP                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Acquisizione dati affidabile in condizioni fluttuanti                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Ideale per applicazioni di stabilit\u00e0, ambientali e di laboratorio                                            <\/span>\r\n                                        <\/li>\r\n                                                                    <\/ul>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                \r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-8f688a6 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/humidity_validation_06.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: bottom left;\r\n        background-size: 54% auto;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-8f688a6 {\r\n            background-position: bottom left;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-8f688a6 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-8f688a6');\r\n        const content = document.getElementById('readmore-content-8f688a6');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6139e63 e-con-full e-flex e-con e-parent\" data-id=\"6139e63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2e06ac elementor-widget elementor-widget-two_columns_with_grid_ellab\" data-id=\"a2e06ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_with_grid_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-with-grid-a2e06ac\" class=\"py-4 py-md-5 px-3 px-md-0 \">\r\n    <div class=\"container position-relative my-4 my-md-5\">\r\n\r\n                <!-- End Agenda Webinar -->\r\n\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n\r\n                                <div class=\"row d-flex align-items-start mb-5\">\r\n                                        <div class=\"col-12 col-12 col-md-8\">\r\n\r\n                                                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-0 mb-5 text-secondary\">\r\n                                <span class=\"text-secondary\">Sensori di umidit\u00e0 <span class=\"text-primary\">costruiti per ambienti controllati e regolamentati<\/span><\/span>                            <\/h2>\r\n                        \r\n                                                    <div class=\"fs-24 fw-semibold text-primary mt-5\">\r\n                                <p>Ellab offre sensori di umidit\u00e0 relativa ad alta precisione progettati per resistere ad ambienti difficili, dalle camere di crescita ad alta umidit\u00e0 ai programmi di stabilit\u00e0 rigorosamente controllati. Ogni sensore \u00e8 progettato per garantire durata, accuratezza e stabilit\u00e0 a lungo termine. <\/p>\n                            <\/div>\r\n                                            <\/div>\r\n\r\n                    \r\n                    <div class=\"col-12 col-12 col-md-4\">\r\n                        <!-- Title -->\r\n                        \r\n                        <!-- Counter -->\r\n                        \r\n                        <!-- Description -->\r\n                        \r\n                        <!-- Custom List -->\r\n                        \r\n                        <!-- Button Right -->\r\n                        \r\n                    <\/div>\r\n                <\/div>\r\n\r\n\r\n                \r\n\r\n\r\n                \r\n                \r\n                \r\n                                    <div class=\"row mb-5\">\r\n                        <div class=\"col-12\">\r\n                            <div class=\"container bg-blur-light rounded-4 p-4 p-md-5\">\r\n                                <div class=\"row\">\r\n                                                                            <div class=\"col-md-6\">\r\n                                            <ul class=\"list-unstyled\">\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Sensore di umidit\u00e0 relativa e temperatura                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Sensori di temperatura                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                            <\/ul>\r\n                                        <\/div>\r\n                                                                            <div class=\"col-md-6\">\r\n                                            <ul class=\"list-unstyled\">\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Sensori di pressione                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Sensori di CO\u2082                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                            <\/ul>\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                \r\n\r\n                \r\n                    <div class=\"col-12 col-md-8 text-start\">\r\n\r\n                                                    <div class=\"fs-36 fw-semibold mb-4 text-primary\">\r\n                                Design dei sensori per misurazioni dell'umidit\u00e0 costanti e ripetibili                            <\/div>\r\n                        \r\n                        \r\n                                                    <div class=\"fs-18 fw-light text-primary\">\r\n                                <p>I nostri sensori mantengono l'accuratezza nonostante le fluttuazioni di temperatura, i rapidi cambiamenti di umidit\u00e0 e i lunghi cicli di qualifica, garantendo risultati conformi e ripetibili senza inutili ripetizioni dei test.<\/p>\n                            <\/div>\r\n                        \r\n                    <\/div>\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n\r\n<style>\r\n    #ellab-two-columns-with-grid-a2e06ac {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/humidity_validation_07.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: center right;\r\n        background-size: contain;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-with-grid-a2e06ac {\r\n            background-position: center right;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    #ellab-two-columns-with-grid-a2e06ac .container {\r\n        @media (min-width: 992px) {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n    .custom-list-wrapper .custom-dot {\r\n        width: 6px;\r\n        height: 6px;\r\n        background-color: #7BC70F;\r\n        \/* Cambia el color del punto *\/\r\n        border-radius: 50%;\r\n        margin-top: 8px;\r\n        \/* alinea con el t\u00edtulo *\/\r\n        flex-shrink: 0;\r\n    }\r\n\r\n    .agenda-col-time {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-col-topic {\r\n        flex: 0 0 60%;\r\n    }\r\n\r\n    .agenda-col-speaker {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-header,\r\n    .agenda-row {\r\n        display: flex;\r\n        align-items: center;\r\n    }\r\n\r\n    \/* LOGO GRID *\/\r\n\r\n    .logos-grid {\r\n        display: grid;\r\n        grid-template-columns: repeat(7, 1fr);\r\n        gap: 24px;\r\n        align-items: center;\r\n    }\r\n\r\n    .logo-item {\r\n        height: 100px;\r\n        \/* todos los logos ocupan la misma altura *\/\r\n        display: flex;\r\n        justify-content: center;\r\n        align-items: center;\r\n        padding: 10px;\r\n    }\r\n\r\n    .logo-item img {\r\n        max-width: 100%;\r\n        max-height: 100%;\r\n        width: auto;\r\n        height: auto;\r\n        object-fit: contain;\r\n    }\r\n\r\n    \/* Tablet *\/\r\n    @media (max-width:991px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(4, 1fr);\r\n        }\r\n    }\r\n\r\n    \/* Mobile *\/\r\n    @media (max-width:767px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(3, 1fr);\r\n            gap: 12px;\r\n        }\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        var countdownEl = document.getElementById('countdown-a2e06ac');\r\n        if (!countdownEl) return;\r\n\r\n        var endDate = new Date('1970-01-01 00:00:00').getTime();\r\n\r\n        function updateCountdown() {\r\n            var now = new Date().getTime();\r\n            var distance = endDate - now;\r\n            if (distance < 0) distance = 0;\r\n\r\n            var days = Math.floor(distance \/ (1000 * 60 * 60 * 24));\r\n            var hours = Math.floor((distance % (1000 * 60 * 60 * 24)) \/ (1000 * 60 * 60));\r\n            var minutes = Math.floor((distance % (1000 * 60 * 60)) \/ (1000 * 60));\r\n            var seconds = Math.floor((distance % (1000 * 60)) \/ 1000);\r\n\r\n            var values = [days, hours, minutes, seconds];\r\n\r\n            var spans = countdownEl.querySelectorAll('[data-count]');\r\n            spans.forEach(function(span, index) {\r\n                span.textContent = values[index].toString().padStart(2, '0');\r\n            });\r\n        }\r\n\r\n        updateCountdown();\r\n        setInterval(updateCountdown, 1000);\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1a3b47 e-con-full e-flex e-con e-parent\" data-id=\"d1a3b47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0481d1 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"e0481d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-e0481d1\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 bg-primary\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-15 text-white\">\r\n                        <span class=\"text-white\">Ottimizza i tuoi studi sull'umidit\u00e0 con un <span class=\"text-secondary\">software di validazione<\/span> pronto per gli audit<\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                                    <div class=\"video-cover position-relative mt-5 mb-5 mb-md-0\" style=\"display:inline-block;\">\r\n\r\n                        <!-- Clickable cover -->\r\n                        <div class=\"video-cover-trigger\"\r\n                            data-video-id=\"\"\r\n                            style=\"cursor:pointer; display:inline-block; position:relative;\">\r\n\r\n                            <!-- Cover image -->\r\n                            \r\n                            <!-- Play icon -->\r\n                                                            <span class=\"play-icon-wrap\">\r\n                                                                    <\/span>\r\n                            \r\n                        <\/div>\r\n\r\n                        <!-- Iframe container (hidden by default) -->\r\n                        <div class=\"video-embed-container\"\r\n                            style=\"display:none; position:absolute; top:0; left:0; width:100%; height:100%; border-radius:1rem; overflow:hidden; z-index:10;\">\r\n                        <\/div>\r\n                    <\/div>\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                                    <div class=\"fs-18 fw-light mb-5 text-white lh-base wysiwyg-list\">\r\n                        <p>Il <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/\">software di validazione di Ellab, ValSuite\u00ae<\/a>, gestisce gli studi sull'umidit\u00e0 relativa con una configurazione intuitiva, una gestione sicura dei dati e una reportistica automatizzata.<\/p>\n<p>Progettato per ambienti GMP, supporta sia studi su camera singola che programmi di riqualificazione multi-sito.<\/p>\n                    <\/div>\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                \r\n                <!-- Paragraph 2 -->\r\n                \r\n                                    <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/\"\r\n                        class=\"btn btn-light btn-sm mt-5\"\r\n                                                >\r\n                        Scopri di pi\u00f9                    <\/a>\r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                                    <div class=\"row g-4 my-4 my-md-5\">\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-primary p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom me-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-icon-1.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Documentazione automatizzata e pronta per gli audit<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-primary p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom me-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-icon-2.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Flussi di dati sicuri e tracciabili<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-primary p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom me-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-icon-3.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Configurazione semplice per camere e stanze controllate<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-primary p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom me-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-icon-4.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Interfacce intuitive per un'esecuzione pi\u00f9 rapida<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-primary p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom me-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-icon-5.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Pienamente in linea con le aspettative normative globali<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                            <\/div>\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                \r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-e0481d1 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/freezer_qualification_data_logger_07.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: top left;\r\n        background-size: contain;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-e0481d1 {\r\n            background-position: top left;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-e0481d1 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-e0481d1');\r\n        const content = document.getElementById('readmore-content-e0481d1');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-526a7d6 e-con-full e-flex e-con e-parent\" data-id=\"526a7d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8eac10 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"d8eac10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-d8eac10\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 bg-success\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-5 mb-5 text-white\">\r\n                        <span class=\"text-white\">Perch\u00e9 i <span class=\"text-primary\">leader del settore<\/span> scelgono Ellab per la validazione dell'umidit\u00e0 relativa<\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                                    <div class=\"fs-18 fw-light mb-5 text-white lh-base wysiwyg-list\">\r\n                        <p>Da decenni, Ellab supporta i processi dipendenti dall'umidit\u00e0 nei <a href=\"https:\/\/www.ellab.com\/it\/life-science\/\">laboratori farmaceutici, biotecnologici e regolamentati<\/a>. I nostri partner si affidano a noi perch\u00e9 forniamo: <\/p>\n<ul>\n<li><strong>Competenza specialistica nell'umidit\u00e0 relativa<\/strong>: profonda conoscenza dei programmi di stabilit\u00e0, delle stanze controllate e della qualifica ambientale.<\/li>\n<li><strong>Un ecosistema completo per la validazione dell'umidit\u00e0 relativa<\/strong>: sensori, logger, calibrazione e supporto alla riqualificazione per studi sull'umidit\u00e0 relativa pienamente conformi.<\/li>\n<li><strong>Portata globale, supporto locale<\/strong>: specialisti che operano in oltre 120 paesi per fornire risultati costanti in tutto il mondo.<\/li>\n<li><strong>Partnership end-to-end<\/strong>: opzioni di supporto flessibili che includono attrezzature, personale e fornitura completa della validazione.<\/li>\n<li><strong>Scelto dai principali produttori<\/strong>: asset dipendenti dall'umidit\u00e0 relativa validati migliaia di volte ogni anno utilizzando i sistemi Ellab.<\/li>\n<\/ul>\n<p>Scegli Ellab per soluzioni di validazione dell'umidit\u00e0 che migliorano la conformit\u00e0, riducono i tempi di inattivit\u00e0 e rafforzano il controllo ambientale.<\/p>\n                    <\/div>\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                \r\n                <!-- Paragraph 2 -->\r\n                                    <span class=\"fs-18 fs-light mb-5 text-white lh-base\"><p>I nostri laboratori di calibrazione forniscono servizi di calibrazione esperti in tutto il mondo. Con strutture strategicamente posizionate e specialisti qualificati, offriamo supporto locale con standard di qualit\u00e0 riconosciuti a livello globale per mantenere le tue apparecchiature precise e conformi. <\/p>\n<p>Indipendentemente da dove ti trovi nel mondo, puoi accedere ai nostri servizi di calibrazione attraverso la nostra rete globale, assicurandoti di ricevere gli stessi elevati standard di precisione e affidabilit\u00e0 ovunque tu sia.<\/p>\n<\/span>\r\n                \r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                \r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-d8eac10 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/green_fullwidth_04.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n        background-size: cover;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-d8eac10 {\r\n            background-position: center center;\r\n            background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/green_fullwidth_04.jpg');\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-d8eac10 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-d8eac10');\r\n        const content = document.getElementById('readmore-content-d8eac10');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c04fe0 e-con-full e-flex e-con e-parent\" data-id=\"8c04fe0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f32c934 elementor-widget elementor-widget-two_columns_with_grid_ellab\" data-id=\"f32c934\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_with_grid_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-with-grid-f32c934\" class=\"py-4 py-md-5 px-3 px-md-0 \">\r\n    <div class=\"container position-relative my-4 my-md-5\">\r\n\r\n                <!-- End Agenda Webinar -->\r\n\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n\r\n                                <div class=\"row d-flex align-items-end mb-5\">\r\n                                        <div class=\"col-12 col-12 col-md-6\">\r\n\r\n                                                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-0 mb-5 text-primary\">\r\n                                <span class=\"text-primary\">Amplia le tue capacit\u00e0 di validazione con le <span class=\"text-secondary\">soluzioni integrate di Ellab<\/span><\/span>                            <\/h2>\r\n                        \r\n                                            <\/div>\r\n\r\n                    \r\n                    <div class=\"col-12 col-12 col-md-6\">\r\n                        <!-- Title -->\r\n                        \r\n                        <!-- Counter -->\r\n                        \r\n                        <!-- Description -->\r\n                                                    <div class=\"fs-24 fw-semibold text-primary mb-4\">\r\n                                <p>Costruisci una strategia di validazione completa per temperatura, CO\u2082, pressione e altro ancora.<\/p>\n                            <\/div>\r\n                        \r\n                        <!-- Custom List -->\r\n                        \r\n                        <!-- Button Right -->\r\n                        \r\n                    <\/div>\r\n                <\/div>\r\n\r\n\r\n                \r\n\r\n\r\n                                    <div class=\"row g-4 align-items-stretch mb-5\">\r\n                                                    <div class=\"col-12 col-md-6 col-lg-4 d-flex mb-2 mb-md-5\">\r\n                                <div class=\"featured-item position-relative text-white rounded-4 overflow-hidden flex-grow-1\"\r\n                                    style=\"background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-grid-1.jpg'); background-size: cover; background-position: center;\">\r\n\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-della-temperatura\/\"\r\n                                            class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                                                                                                                    aria-hidden=\"true\" tabindex=\"-1\" style=\"z-index: 3;\">\r\n                                        <\/a>\r\n                                    \r\n                                    <!-- Gradient overlay -->\r\n                                                                        <!--<div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                            style=\"\">\r\n                                        <\/div>-->\r\n                                                                        <div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                        style=\"background: linear-gradient(to right, rgb(17 45 55 \/ 53%) 100%, rgba(var(--bs-primary-rgb), 0.55) 60%, transparent 100%); z-index: 1;\">\r\n                                    <\/div>\r\n                                    \r\n                                    <div class=\"p-4 p-md-5 d-flex flex-column h-100 justify-content-start position-relative\"\r\n                                        style=\"z-index: 2;\">\r\n\r\n                                        <h3 class=\"fs-20 fw-semibold my-3 text-white\">\r\n                                            Validazione della temperatura                                        <\/h3>\r\n\r\n                                                                                    <p class=\"fs-15 text-white mb-3\">\r\n                                                Hardware leader del settore per la validazione ad alta e bassa temperatura.                                            <\/p>\r\n                                        \r\n                                                                                    <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-della-temperatura\/\"\r\n                                                class=\"text-white fw-semibold fs-15 position-relative\"\r\n                                                                                                >\r\n                                                Esplora la validazione della temperatura                                            <\/a>\r\n                                        \r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12 col-md-6 col-lg-4 d-flex mb-2 mb-md-5\">\r\n                                <div class=\"featured-item position-relative text-white rounded-4 overflow-hidden flex-grow-1\"\r\n                                    style=\"background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-grid-2.jpg'); background-size: cover; background-position: center;\">\r\n\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-della-co2\/\"\r\n                                            class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                                                                                                                    aria-hidden=\"true\" tabindex=\"-1\" style=\"z-index: 3;\">\r\n                                        <\/a>\r\n                                    \r\n                                    <!-- Gradient overlay -->\r\n                                                                        <!--<div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                            style=\"\">\r\n                                        <\/div>-->\r\n                                                                        <div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                        style=\"background: linear-gradient(to right, rgb(17 45 55 \/ 53%) 100%, rgba(var(--bs-primary-rgb), 0.55) 60%, transparent 100%); z-index: 1;\">\r\n                                    <\/div>\r\n                                    \r\n                                    <div class=\"p-4 p-md-5 d-flex flex-column h-100 justify-content-start position-relative\"\r\n                                        style=\"z-index: 2;\">\r\n\r\n                                        <h3 class=\"fs-20 fw-semibold my-3 text-white\">\r\n                                            Validazione della CO\u2082                                        <\/h3>\r\n\r\n                                                                                    <p class=\"fs-15 text-white mb-3\">\r\n                                                Strumenti di misurazione precisi per ambienti controllati da CO\u2082.                                            <\/p>\r\n                                        \r\n                                                                                    <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-della-co2\/\"\r\n                                                class=\"text-white fw-semibold fs-15 position-relative\"\r\n                                                                                                >\r\n                                                Esplora la validazione della CO\u2082                                            <\/a>\r\n                                        \r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12 col-md-6 col-lg-4 d-flex mb-2 mb-md-5\">\r\n                                <div class=\"featured-item position-relative text-white rounded-4 overflow-hidden flex-grow-1\"\r\n                                    style=\"background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/WORKING_AT_ELLAB_05A.jpg'); background-size: cover; background-position: center;\">\r\n\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-della-pressione-e-del-vuoto\/\"\r\n                                            class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                                                                                                                    aria-hidden=\"true\" tabindex=\"-1\" style=\"z-index: 3;\">\r\n                                        <\/a>\r\n                                    \r\n                                    <!-- Gradient overlay -->\r\n                                                                        <!--<div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                            style=\"\">\r\n                                        <\/div>-->\r\n                                                                        <div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                        style=\"background: linear-gradient(to right, rgb(17 45 55 \/ 53%) 100%, rgba(var(--bs-primary-rgb), 0.55) 60%, transparent 100%); z-index: 1;\">\r\n                                    <\/div>\r\n                                    \r\n                                    <div class=\"p-4 p-md-5 d-flex flex-column h-100 justify-content-start position-relative\"\r\n                                        style=\"z-index: 2;\">\r\n\r\n                                        <h3 class=\"fs-20 fw-semibold my-3 text-white\">\r\n                                            Validazione della pressione                                        <\/h3>\r\n\r\n                                                                                    <p class=\"fs-15 text-white mb-3\">\r\n                                                Registrazione e misurazione affidabili per applicazioni critiche per la pressione.                                            <\/p>\r\n                                        \r\n                                                                                    <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-della-pressione-e-del-vuoto\/\"\r\n                                                class=\"text-white fw-semibold fs-15 position-relative\"\r\n                                                                                                >\r\n                                                Esplora la validazione della pressione                                            <\/a>\r\n                                        \r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                            <\/div>\r\n                \r\n                \r\n                \r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n\r\n<style>\r\n    #ellab-two-columns-with-grid-f32c934 {\r\n        background-image: url('');\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n        background-size: contain;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-with-grid-f32c934 {\r\n            background-position: center center;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    #ellab-two-columns-with-grid-f32c934 .container {\r\n        @media (min-width: 992px) {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n    .custom-list-wrapper .custom-dot {\r\n        width: 6px;\r\n        height: 6px;\r\n        background-color: #7BC70F;\r\n        \/* Cambia el color del punto *\/\r\n        border-radius: 50%;\r\n        margin-top: 8px;\r\n        \/* alinea con el t\u00edtulo *\/\r\n        flex-shrink: 0;\r\n    }\r\n\r\n    .agenda-col-time {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-col-topic {\r\n        flex: 0 0 60%;\r\n    }\r\n\r\n    .agenda-col-speaker {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-header,\r\n    .agenda-row {\r\n        display: flex;\r\n        align-items: center;\r\n    }\r\n\r\n    \/* LOGO GRID *\/\r\n\r\n    .logos-grid {\r\n        display: grid;\r\n        grid-template-columns: repeat(7, 1fr);\r\n        gap: 24px;\r\n        align-items: center;\r\n    }\r\n\r\n    .logo-item {\r\n        height: 100px;\r\n        \/* todos los logos ocupan la misma altura *\/\r\n        display: flex;\r\n        justify-content: center;\r\n        align-items: center;\r\n        padding: 10px;\r\n    }\r\n\r\n    .logo-item img {\r\n        max-width: 100%;\r\n        max-height: 100%;\r\n        width: auto;\r\n        height: auto;\r\n        object-fit: contain;\r\n    }\r\n\r\n    \/* Tablet *\/\r\n    @media (max-width:991px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(4, 1fr);\r\n        }\r\n    }\r\n\r\n    \/* Mobile *\/\r\n    @media (max-width:767px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(3, 1fr);\r\n            gap: 12px;\r\n        }\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        var countdownEl = document.getElementById('countdown-f32c934');\r\n        if (!countdownEl) return;\r\n\r\n        var endDate = new Date('1970-01-01 00:00:00').getTime();\r\n\r\n        function updateCountdown() {\r\n            var now = new Date().getTime();\r\n            var distance = endDate - now;\r\n            if (distance < 0) distance = 0;\r\n\r\n            var days = Math.floor(distance \/ (1000 * 60 * 60 * 24));\r\n            var hours = Math.floor((distance % (1000 * 60 * 60 * 24)) \/ (1000 * 60 * 60));\r\n            var minutes = Math.floor((distance % (1000 * 60 * 60)) \/ (1000 * 60));\r\n            var seconds = Math.floor((distance % (1000 * 60)) \/ 1000);\r\n\r\n            var values = [days, hours, minutes, seconds];\r\n\r\n            var spans = countdownEl.querySelectorAll('[data-count]');\r\n            spans.forEach(function(span, index) {\r\n                span.textContent = values[index].toString().padStart(2, '0');\r\n            });\r\n        }\r\n\r\n        updateCountdown();\r\n        setInterval(updateCountdown, 1000);\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Validazione affidabile dell&#8217;umidit\u00e0 relativa per ambienti regolamentati Misurazioni dell&#039;umidit\u00e0 relativa ad alta precisione, apparecchiature affidabili e conformit\u00e0 garantita. Dalle camere di stabilit\u00e0 alle celle ambientali e agli spazi di laboratorio controllati, i sistemi di validazione dell&#039;umidit\u00e0 di Ellab forniscono dati precisi e tracciabili sull&#039;umidit\u00e0 relativa in un ampio intervallo di misurazione. I nostri data logger [&hellip;]<\/p>\n","protected":false},"author":2456,"featured_media":0,"parent":17702,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/modules.php","meta":{"footnotes":""},"class_list":["post-17063","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Validazione dell&#039;umidit\u00e0 per ambienti regolamentati | Ellab<\/title>\n<meta name=\"description\" content=\"Dalle camere di stabilit\u00e0 alle celle ambientali e agli spazi di laboratorio controllati, i sistemi di validazione dell&#039;umidit\u00e0 di Ellab forniscono dati precisi e tracciabili sull&#039;umidit\u00e0 relativa in un ampio intervallo di misurazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Validazione dell&#039;umidit\u00e0\" \/>\n<meta property=\"og:description\" content=\"Dalle camere di stabilit\u00e0 alle celle ambientali e agli spazi di laboratorio controllati, i sistemi di validazione dell&#039;umidit\u00e0 di Ellab forniscono dati precisi e tracciabili sull&#039;umidit\u00e0 relativa in un ampio intervallo di misurazione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellab\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T14:56:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/applications-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/convalida-dellumidita\\\/\",\"url\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/convalida-dellumidita\\\/\",\"name\":\"Validazione dell'umidit\u00e0 per ambienti regolamentati | Ellab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/convalida-dellumidita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/convalida-dellumidita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ellab.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/applications-1.jpg\",\"datePublished\":\"2026-02-23T11:28:50+00:00\",\"dateModified\":\"2026-03-25T14:56:25+00:00\",\"description\":\"Dalle camere di stabilit\u00e0 alle celle ambientali e agli spazi di laboratorio controllati, i sistemi di validazione dell'umidit\u00e0 di Ellab forniscono dati precisi e tracciabili sull'umidit\u00e0 relativa in un ampio intervallo di misurazione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/convalida-dellumidita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/convalida-dellumidita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/convalida-dellumidita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ellab.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/applications-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ellab.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/applications-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/convalida-dellumidita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Validazione\",\"item\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sistemi di convalida\",\"item\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Validazione dell&#8217;umidit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/\",\"name\":\"Ellab\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Validazione dell'umidit\u00e0 per ambienti regolamentati | Ellab","description":"Dalle camere di stabilit\u00e0 alle celle ambientali e agli spazi di laboratorio controllati, i sistemi di validazione dell'umidit\u00e0 di Ellab forniscono dati precisi e tracciabili sull'umidit\u00e0 relativa in un ampio intervallo di misurazione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/","og_locale":"it_IT","og_type":"article","og_title":"Validazione dell'umidit\u00e0","og_description":"Dalle camere di stabilit\u00e0 alle celle ambientali e agli spazi di laboratorio controllati, i sistemi di validazione dell'umidit\u00e0 di Ellab forniscono dati precisi e tracciabili sull'umidit\u00e0 relativa in un ampio intervallo di misurazione.","og_url":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/","og_site_name":"Ellab","article_modified_time":"2026-03-25T14:56:25+00:00","og_image":[{"url":"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/applications-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/","url":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/","name":"Validazione dell'umidit\u00e0 per ambienti regolamentati | Ellab","isPartOf":{"@id":"https:\/\/www.ellab.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/#primaryimage"},"image":{"@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/applications-1.jpg","datePublished":"2026-02-23T11:28:50+00:00","dateModified":"2026-03-25T14:56:25+00:00","description":"Dalle camere di stabilit\u00e0 alle celle ambientali e agli spazi di laboratorio controllati, i sistemi di validazione dell'umidit\u00e0 di Ellab forniscono dati precisi e tracciabili sull'umidit\u00e0 relativa in un ampio intervallo di misurazione.","breadcrumb":{"@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/#primaryimage","url":"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/applications-1.jpg","contentUrl":"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/applications-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/convalida-dellumidita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ellab.com\/it\/"},{"@type":"ListItem","position":2,"name":"Validazione","item":"https:\/\/www.ellab.com\/it\/convalida\/"},{"@type":"ListItem","position":3,"name":"Sistemi di convalida","item":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/"},{"@type":"ListItem","position":4,"name":"Validazione dell&#8217;umidit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.ellab.com\/it\/#website","url":"https:\/\/www.ellab.com\/it\/","name":"Ellab","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ellab.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/17063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/users\/2456"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/comments?post=17063"}],"version-history":[{"count":2,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/17063\/revisions"}],"predecessor-version":[{"id":20626,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/17063\/revisions\/20626"}],"up":[{"embeddable":true,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/17702"}],"wp:attachment":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/media?parent=17063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}