{"id":18136,"date":"2026-02-23T12:28:29","date_gmt":"2026-02-23T11:28:29","guid":{"rendered":"https:\/\/www.ellab.com\/validazione\/sistemi-di-convalida\/software-di-validazione\/"},"modified":"2026-05-14T16:27:15","modified_gmt":"2026-05-14T14:27:15","slug":"software-di-convalida","status":"publish","type":"page","link":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/","title":{"rendered":"Software di validazione"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18136\" class=\"elementor elementor-18136 elementor-8855\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b68b90 e-con-full e-flex e-con e-parent\" data-id=\"8b68b90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7fe102 elementor-widget elementor-widget-hero_ellab\" data-id=\"f7fe102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hero_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-hero-f7fe102\" class=\"d-flex align-items-center px-3 px-md-0 \" style=\"min-height: 100vh;\">\r\n    <div class=\"container\">\r\n        <div class=\"row justify-content-start\">\r\n\r\n            \r\n            <div class=\"col-12 col-md-12\">\r\n\r\n\r\n                \r\n                \r\n                                    <h1 class=\"custom-title fs-56 fw-semibold mb-5 text-secondary\">\r\n                        <span class=\"text-secondary\"><span class=\"text-white\">Software di validazione<\/span> ValSuite\u00ae<\/span>                    <\/h1>\r\n                \r\n                \r\n                                    <h6 class=\"hero-subtitle fs-24 fw-semibold mb-4 text-white w-100 w-md-100\">\r\n                        Ottimizza validazione e calibrazione: garantisci la conformit\u00e0, risparmia tempo e ottieni il controllo completo                    <\/h6>\r\n                \r\n                                    <p class=\"fs-24 fw-light mb-4 text-white w-100 w-md-75\">\r\n                        La gestione manuale dei dati e i sistemi frammentati aumentano i rischi di conformit\u00e0 e fanno perdere tempo prezioso. ValSuite\u00ae riunisce tutti i tuoi dati di validazione e calibrazione in un&#039;unica piattaforma intuitiva, automatizzando la documentazione, garantendo la conformit\u00e0 normativa e offrendoti approfondimenti in tempo reale per decisioni pi\u00f9 rapide e intelligenti.                     <\/p>\r\n                \r\n                                                        <a href=\"#popmake-7957\"\r\n                        class=\"btn btn-sm mt-4 btn-light\"\r\n                        >\r\n                        Richiedi una demo gratuita                    <\/a>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n<style>\r\n    #ellab-hero-f7fe102 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/validation_software_01.jpg');\r\n        background-size: cover;\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        #ellab-hero-f7fe102 {\r\n            background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/validation_software_01.jpg');\r\n            background-position: center center;\r\n        }\r\n    }\r\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d2dd4da e-con-full e-flex e-con e-parent\" data-id=\"d2dd4da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-626be23 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"626be23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-626be23\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 \">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-primary sticky-xl-top\">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-5 text-primary\">\r\n                        <span class=\"text-primary\">Trasforma le sfide della conformit\u00e0 in un <span class=\"text-secondary\">vantaggio competitivo<\/span><\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                                    <div class=\"video-cover position-relative mt-5 mb-5 mb-md-0\" style=\"display:inline-block;\">\r\n\r\n                        <!-- Clickable cover -->\r\n                        <div class=\"video-cover-trigger\"\r\n                            data-video-id=\"\"\r\n                            style=\"cursor:pointer; display:inline-block; position:relative;\">\r\n\r\n                            <!-- Cover image -->\r\n                            \r\n                            <!-- Play icon -->\r\n                                                            <span class=\"play-icon-wrap\">\r\n                                                                    <\/span>\r\n                            \r\n                        <\/div>\r\n\r\n                        <!-- Iframe container (hidden by default) -->\r\n                        <div class=\"video-embed-container\"\r\n                            style=\"display:none; position:absolute; top:0; left:0; width:100%; height:100%; border-radius:1rem; overflow:hidden; z-index:10;\">\r\n                        <\/div>\r\n                    <\/div>\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-primary\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                                    <div class=\"fs-18 fw-light mb-5 text-primary lh-base wysiwyg-list\">\r\n                        <p>I flussi di lavoro tradizionali di validazione e calibrazione sono rallentati dall'inserimento manuale dei dati, da una reportistica complessa e dal rischio di errore umano. ValSuite\u00ae elimina questi punti critici grazie a una raccolta dati sicura e automatizzata, modelli di test personalizzabili e generazione istantanea di report. <\/p>\n<p>Con una tracciabilit\u00e0 completa e una documentazione pronta per gli audit, puoi soddisfare con sicurezza i requisiti normativi pi\u00f9 severi, permettendo al tuo team di concentrarsi su ci\u00f2 che conta di pi\u00f9.<\/p>\n<p><strong>La combinazione perfetta per:<\/strong><\/p>\n                    <\/div>\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                \r\n                <!-- Paragraph 2 -->\r\n                \r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                                    <div class=\"row g-4 my-4 my-md-5\">\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-light p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom mb-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Validazione termica di sterilizzatori, autoclavi e liofilizzatori<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-light p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom mb-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Monitoraggio ambientale in camere bianche e magazzini<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-light p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom mb-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Calibrazione di temperatura, umidit\u00e0, pressione e altro ancora <\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-light p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom mb-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Gestione dell'integrit\u00e0 dei dati per gli audit normativi<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-light p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom mb-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Monitoraggio dei processi in tempo reale e notifiche di allarme<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-light p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom mb-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Progetti di validazione multi-sito e multi-dispositivo<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                            <\/div>\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                \r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-626be23 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/04\/Software-ValSuite-Showcase-bright.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: bottom left;\r\n        background-size: 69% auto;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-626be23 {\r\n            background-position: bottom left;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-626be23 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-626be23');\r\n        const content = document.getElementById('readmore-content-626be23');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f66091 e-con-full e-flex e-con e-parent\" data-id=\"2f66091\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45d7bf8 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"45d7bf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-45d7bf8\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 bg-success\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-5 mb-5 text-white\">\r\n                        <span class=\"text-white\">Sperimenta una conformit\u00e0 senza sforzo - Richiedi la tua demo gratuita di ValSuite\u00ae<\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                                    <h6 class=\"fs-24 fw-semibold mb-4 text-white\">\r\n                        Scopri come ValSuite\u00ae pu\u00f2 semplificare i tuoi processi di validazione e calibrazione, ridurre lo stress da audit e darti il controllo completo sui tuoi dati. Richiedi una demo personalizzata e scopri tu stesso la differenza                     <\/h6>\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                \r\n                <!-- Paragraph 2 -->\r\n                \r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                <iframe class=\"pardotform\" src=\"https:\/\/www2.ellab.com\/l\/971953\/2022-08-30\/9hwy\" width=\"100%\" height=\"680\" frameborder=\"0\" pardot-form-name=\"IT-Contact-Ellab\"><\/iframe>\r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-45d7bf8 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/img_form_module-2.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n        background-size: cover;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-45d7bf8 {\r\n            background-position: center center;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-45d7bf8 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-45d7bf8');\r\n        const content = document.getElementById('readmore-content-45d7bf8');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54530fb e-con-full e-flex e-con e-parent\" data-id=\"54530fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89acab8 elementor-widget elementor-widget-testimonial_ellab\" data-id=\"89acab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-testimonial-89acab8\" class=\"section-carousel testimonial-carousel py-4 py-lg-5 px-3 px-md-0\" aria-label=\"Testimonials Carousel\">\r\n    <div class=\"container my-4 my-lg-5\">\r\n        <div class=\"row justify-content-center\">\r\n            <div class=\"col-12 col-md-10 mx-auto\">\r\n                <div class=\"row justify-content-center\">\r\n                    <div class=\"col-12\">\r\n\r\n                        \r\n                                                    <h3 class=\"custom-title fs-36 fw-semibold mb-5 text-center text-primary\">\r\n                                <span class=\"text-primary\"><\/span>                            <\/h3>\r\n                        \r\n\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                                    <div class=\"splide\" id=\"testimonial-splide-89acab8\">\r\n                        <div class=\"splide__track\">\r\n                            <ul class=\"splide__list\">\r\n                                                                    <li class=\"splide__slide\">\r\n                                        <div class=\"bg-gradient-light p-5 rounded-4\">\r\n                                            <div class=\"row align-items-start\">\r\n                                                <div class=\"col-auto col-md-1 d-flex justify-content-center justify-content-md-start\">\r\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/quote.svg\"\r\n                                                            alt=\"Quote Mark\"\r\n                                                            class=\"quote-mark\" \/>\r\n                                                                                                    <\/div>\r\n                                                <div class=\"col-12 col-md-11\">\r\n                                                    <blockquote class=\"flex-grow-1 ms-0 ms-md-5 mb-0 mb-md-4\">\r\n                                                        <div class=\"fs-20 fst-italic mb-5 text-start\">\r\n                                                            <p>Ellab ci fornisce uno dei data logger pi\u00f9 affidabili e un software intuitivo. Con i risultati di un fornitore di servizi di prima classe e un eccellente servizio clienti, Ellab non \u00e8 solo un fornitore di tecnologia di misurazione, ma piuttosto un centro di competenza per i compiti sempre pi\u00f9 impegnativi nel campo della validazione dei processi termici. <\/p>\n                                                        <\/div>\r\n                                                    <\/blockquote>\r\n                                                <\/div>\r\n                                                <footer class=\"text-center py-md-4 py-4\">\r\n                                                    <div class=\"fs-15 text-dark fw-bold\">Johann Prenn<\/div>\r\n                                                    <div class=\"fs-15 text-secondary fw-bold\">Mars Austria OG<\/div>\r\n                                                    <div class=\"fs-13 text-muted fw-bold\"><\/div>\r\n                                                    <div class=\"fs-13 text-muted\"><\/div>\r\n                                                <\/footer>\r\n                                            <\/div>\r\n\r\n                                        <\/div>\r\n                                    <\/li>\r\n                                                                    <li class=\"splide__slide\">\r\n                                        <div class=\"bg-gradient-light p-5 rounded-4\">\r\n                                            <div class=\"row align-items-start\">\r\n                                                <div class=\"col-auto col-md-1 d-flex justify-content-center justify-content-md-start\">\r\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/quote.svg\"\r\n                                                            alt=\"Quote Mark\"\r\n                                                            class=\"quote-mark\" \/>\r\n                                                                                                    <\/div>\r\n                                                <div class=\"col-12 col-md-11\">\r\n                                                    <blockquote class=\"flex-grow-1 ms-0 ms-md-5 mb-0 mb-md-4\">\r\n                                                        <div class=\"fs-20 fst-italic mb-5 text-start\">\r\n                                                            <p>Ellab \u00e8 il futuro dei sensori termici secondo la mia opinione ed esperienza personale. Consiglio vivamente il loro hardware e software, anche il loro supporto clienti \u00e8 eccezionale!  Grazie Ellab!<\/p>\n                                                        <\/div>\r\n                                                    <\/blockquote>\r\n                                                <\/div>\r\n                                                <footer class=\"text-center py-md-4 py-4\">\r\n                                                    <div class=\"fs-15 text-dark fw-bold\">Matt Hatfield<\/div>\r\n                                                    <div class=\"fs-15 text-secondary fw-bold\">Bausch and Lomb<\/div>\r\n                                                    <div class=\"fs-13 text-muted fw-bold\"><\/div>\r\n                                                    <div class=\"fs-13 text-muted\"><\/div>\r\n                                                <\/footer>\r\n                                            <\/div>\r\n\r\n                                        <\/div>\r\n                                    <\/li>\r\n                                                            <\/ul>\r\n                        <\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n\r\n<style>\r\n    #ellab-testimonial-89acab8 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/home_img_bg_6.png');\r\n        background-size: auto;\r\n        background-repeat: no-repeat;\r\n        background-position: center left;\r\n    }\r\n\r\n    @media (max-width: 991px) {\r\n        #ellab-testimonial-89acab8 {\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    #testimonial-splide-89acab8 .splide__pagination__page {\r\n        background: #d3d3d3 !important;\r\n        border: none !important;\r\n        opacity: 1 !important;\r\n        width: 6px !important;\r\n        height: 6px !important;\r\n        margin: 0 6px !important;\r\n    }\r\n\r\n    #testimonial-splide-89acab8 .splide__pagination__page.is-active {\r\n        background: var(--bs-primary) !important;\r\n        transform: scale(1.8) !important;\r\n    }\r\n\r\n    #testimonial-splide-89acab8 .bg-gradient-light {\r\n        background: linear-gradient(to right,\r\n                rgba(241, 242, 244, 0.6) 0%,\r\n                rgba(241, 242, 244, 0.85) 40%);\r\n    }\r\n\r\n\r\n    .elementor .quote-mark {\r\n        width: 200px;\r\n        max-width: none;\r\n        height: auto;\r\n        margin-bottom: 0;\r\n        \/* o lo que necesites *\/\r\n    }\r\n\r\n    @media (max-width: 1024px) {\r\n        .elementor .quote-mark {\r\n            width: 120px;\r\n            margin-bottom: 30px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767.98px) {\r\n        .elementor .quote-mark {\r\n            width: 60px;\r\n            margin-bottom: 30px;\r\n        }\r\n    }\r\n<\/style>\r\n\r\n\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        if (typeof Splide !== 'undefined') {\r\n            new Splide('#testimonial-splide-89acab8', {\r\n                type: 'loop',\r\n                perPage: 1,\r\n                arrows: false,\r\n                pagination: true,\r\n                autoplay: true,\r\n                interval: 5000,\r\n                pauseOnHover: true,\r\n                classes: {\r\n                    pagination: 'splide__pagination mt-4 text-center',\r\n                    page: 'splide__pagination__page',\r\n                },\r\n            }).mount();\r\n        }\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2aa3b7b e-con-full e-flex e-con e-parent\" data-id=\"2aa3b7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f688a6 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"8f688a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-8f688a6\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 bg-primary\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-5 mb-5 text-white\">\r\n                        <span class=\"text-white\">Perch\u00e9 ValSuite\u00ae <span class=\"text-secondary\">definisce lo standard<\/span><\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                                    <div class=\"fs-18 fw-light mb-5 text-white lh-base wysiwyg-list\">\r\n                        <p>ValSuite\u00ae riunisce tutto ci\u00f2 di cui hai bisogno sotto lo stesso tetto: smetti di destreggiarti tra pi\u00f9 fogli di calcolo e ottieni un unico software che comunica direttamente con i tuoi data logger e sistemi a termocoppia Ellab.<\/p>\n<p>Basato su una struttura SQL sicura, ValSuite\u00ae mantiene i tuoi dati pronti per gli audit e al sicuro. E grazie alla sua interfaccia intuitiva e alla configurazione rapida, i team possono essere operativi in pochi giorni invece che in settimane. <\/p>\n                    <\/div>\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                                                        <h6 class=\"fs-36 fw-semibold mt-5 mb-4 text-white\">\r\n                        Tutto ci\u00f2 di cui hai bisogno in un unico software                    <\/h6>\r\n                \r\n                <!-- Paragraph 2 -->\r\n                \r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                                    <div class=\"row g-4 \">\r\n                                            <\/div>\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                                    <div class=\"row pt-5\">\r\n                        <div class=\"col-12\">\r\n                            <div class=\"container bg-blur-primary rounded-4 p-4 p-md-5\">\r\n                                <ul class=\"list-unstyled\">\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Un&#039;unica piattaforma per tutte le apparecchiature di validazione e calibrazione Ellab                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Conforme a FDA 21 CFR Part 11 e GAMP 5 per la piena integrit\u00e0 dei dati                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Reportistica automatizzata e personalizzabile con chiari criteri di superamento\/fallimento                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Monitoraggio in tempo reale, dati live e analisi avanzate                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Interfaccia user-friendly con supporto multilingue                                            <\/span>\r\n                                        <\/li>\r\n                                                                    <\/ul>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                \r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-8f688a6 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/validation_software_05.png');\r\n        background-repeat: no-repeat;\r\n        background-position: bottom left;\r\n        background-size: 55% auto;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-8f688a6 {\r\n            background-position: bottom left;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-8f688a6 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-8f688a6');\r\n        const content = document.getElementById('readmore-content-8f688a6');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6139e63 e-con-full e-flex e-con e-parent\" data-id=\"6139e63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2e06ac elementor-widget elementor-widget-two_columns_with_grid_ellab\" data-id=\"a2e06ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_with_grid_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-with-grid-a2e06ac\" class=\"py-4 py-md-5 px-3 px-md-0 \">\r\n    <div class=\"container position-relative my-4 my-md-5\">\r\n\r\n                <!-- End Agenda Webinar -->\r\n\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n\r\n                                <div class=\"row d-flex align-items-start mb-5\">\r\n                                        <div class=\"col-12 col-12 col-md-8\">\r\n\r\n                                                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-0 mb-5 text-secondary\">\r\n                                <span class=\"text-secondary\">Cosa traccia ValSuite\u00ae: parametri chiave e sensori di cui ti puoi fidare<\/span>                            <\/h2>\r\n                        \r\n                                                    <div class=\"fs-24 fw-semibold text-primary mt-5\">\r\n                                <p>ValSuite\u00ae tiene d'occhio parametri essenziali come la temperatura (da -90 \u00b0C a +400 \u00b0C), il vuoto, la CO\u2082, la pressione, l'umidit\u00e0 relativa e la conducibilit\u00e0. Dotato di un'ampia selezione di sensori e sonde che supportano la calibrazione da parte dell'utente, garantisce misurazioni precise e affidabili, studiate per compiti critici di validazione e monitoraggio in contesti farmaceutici, di laboratorio e industriali. <\/p>\n                            <\/div>\r\n                                            <\/div>\r\n\r\n                    \r\n                    <div class=\"col-12 col-12 col-md-4\">\r\n                        <!-- Title -->\r\n                        \r\n                        <!-- Counter -->\r\n                        \r\n                        <!-- Description -->\r\n                        \r\n                        <!-- Custom List -->\r\n                        \r\n                        <!-- Button Right -->\r\n                        \r\n                    <\/div>\r\n                <\/div>\r\n\r\n\r\n                \r\n\r\n\r\n                \r\n                \r\n                \r\n                                    <div class=\"row mb-5\">\r\n                        <div class=\"col-12\">\r\n                            <div class=\"container bg-blur-light rounded-4 p-4 p-md-5\">\r\n                                <div class=\"row\">\r\n                                                                            <div class=\"col-md-4\">\r\n                                            <ul class=\"list-unstyled\">\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Temperatura (da -90\u00b0 a +400 \u00b0C)                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Vuoto                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            CO\u2082                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                            <\/ul>\r\n                                        <\/div>\r\n                                                                            <div class=\"col-md-4\">\r\n                                            <ul class=\"list-unstyled\">\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Pressione                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Umidit\u00e0 relativa                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Conduttivit\u00e0                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                            <\/ul>\r\n                                        <\/div>\r\n                                                                            <div class=\"col-md-4\">\r\n                                            <ul class=\"list-unstyled\">\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Dati in tempo reale                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                            <\/ul>\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                \r\n\r\n                \r\n                    <div class=\"col-12 col-md-8 text-start\">\r\n\r\n                                                    <div class=\"fs-36 fw-semibold mb-4 text-primary\">\r\n                                Approfondimenti in tempo reale: sfruttare i dati live per decisioni pi\u00f9 intelligenti                            <\/div>\r\n                        \r\n                        \r\n                                                    <div class=\"fs-18 fw-light text-primary\">\r\n                                <p>Con lo streaming di dati in tempo reale da tutti i sensori collegati, ValSuite\u00ae ti permette di individuare istantaneamente le deviazioni e prendere decisioni rapide e informate, aiutandoti a mantenere una conformit\u00e0 continua e a ottimizzare i tuoi processi senza ritardi.<\/p>\n                            <\/div>\r\n                        \r\n                    <\/div>\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n\r\n<style>\r\n    #ellab-two-columns-with-grid-a2e06ac {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-img-8.png');\r\n        background-repeat: no-repeat;\r\n        background-position: center right;\r\n        background-size: contain;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-with-grid-a2e06ac {\r\n            background-position: center right;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    #ellab-two-columns-with-grid-a2e06ac .container {\r\n        @media (min-width: 992px) {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n    .custom-list-wrapper .custom-dot {\r\n        width: 6px;\r\n        height: 6px;\r\n        background-color: #7BC70F;\r\n        \/* Cambia el color del punto *\/\r\n        border-radius: 50%;\r\n        margin-top: 8px;\r\n        \/* alinea con el t\u00edtulo *\/\r\n        flex-shrink: 0;\r\n    }\r\n\r\n    .agenda-col-time {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-col-topic {\r\n        flex: 0 0 60%;\r\n    }\r\n\r\n    .agenda-col-speaker {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-header,\r\n    .agenda-row {\r\n        display: flex;\r\n        align-items: center;\r\n    }\r\n\r\n    \/* LOGO GRID *\/\r\n\r\n    .logos-grid {\r\n        display: grid;\r\n        grid-template-columns: repeat(7, 1fr);\r\n        gap: 24px;\r\n        align-items: center;\r\n    }\r\n\r\n    .logo-item {\r\n        height: 100px;\r\n        \/* todos los logos ocupan la misma altura *\/\r\n        display: flex;\r\n        justify-content: center;\r\n        align-items: center;\r\n        padding: 10px;\r\n    }\r\n\r\n    .logo-item img {\r\n        max-width: 100%;\r\n        max-height: 100%;\r\n        width: auto;\r\n        height: auto;\r\n        object-fit: contain;\r\n    }\r\n\r\n    \/* Tablet *\/\r\n    @media (max-width:991px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(4, 1fr);\r\n        }\r\n    }\r\n\r\n    \/* Mobile *\/\r\n    @media (max-width:767px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(3, 1fr);\r\n            gap: 12px;\r\n        }\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        var countdownEl = document.getElementById('countdown-a2e06ac');\r\n        if (!countdownEl) return;\r\n\r\n        var endDate = new Date('1970-01-01 00:00:00').getTime();\r\n\r\n        function updateCountdown() {\r\n            var now = new Date().getTime();\r\n            var distance = endDate - now;\r\n            if (distance < 0) distance = 0;\r\n\r\n            var days = Math.floor(distance \/ (1000 * 60 * 60 * 24));\r\n            var hours = Math.floor((distance % (1000 * 60 * 60 * 24)) \/ (1000 * 60 * 60));\r\n            var minutes = Math.floor((distance % (1000 * 60 * 60)) \/ (1000 * 60));\r\n            var seconds = Math.floor((distance % (1000 * 60)) \/ 1000);\r\n\r\n            var values = [days, hours, minutes, seconds];\r\n\r\n            var spans = countdownEl.querySelectorAll('[data-count]');\r\n            spans.forEach(function(span, index) {\r\n                span.textContent = values[index].toString().padStart(2, '0');\r\n            });\r\n        }\r\n\r\n        updateCountdown();\r\n        setInterval(updateCountdown, 1000);\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1a3b47 e-con-full e-flex e-con e-parent\" data-id=\"d1a3b47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0481d1 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"e0481d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-e0481d1\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 bg-primary\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-15 text-white\">\r\n                        <span class=\"text-white\"><span class=\"text-secondary\">Hardware di validazione<\/span> affidabile per ogni applicazione<\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                                    <div class=\"video-cover position-relative mt-5 mb-5 mb-md-0\" style=\"display:inline-block;\">\r\n\r\n                        <!-- Clickable cover -->\r\n                        <div class=\"video-cover-trigger\"\r\n                            data-video-id=\"\"\r\n                            style=\"cursor:pointer; display:inline-block; position:relative;\">\r\n\r\n                            <!-- Cover image -->\r\n                            \r\n                            <!-- Play icon -->\r\n                                                            <span class=\"play-icon-wrap\">\r\n                                                                    <\/span>\r\n                            \r\n                        <\/div>\r\n\r\n                        <!-- Iframe container (hidden by default) -->\r\n                        <div class=\"video-embed-container\"\r\n                            style=\"display:none; position:absolute; top:0; left:0; width:100%; height:100%; border-radius:1rem; overflow:hidden; z-index:10;\">\r\n                        <\/div>\r\n                    <\/div>\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                                    <div class=\"fs-18 fw-light mb-5 text-white lh-base wysiwyg-list\">\r\n                        <p>Ellab offre una gamma completa di apparecchiature di validazione progettate sia per la flessibilit\u00e0 che per la conformit\u00e0. Scegli tra <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/datalogger-senza-fili\/\">data logger wireless avanzati<\/a> per una facile implementazione in ambienti difficili, o <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/sistema-di-convalida-cablato\/\">robusti sistemi cablati<\/a> che offrono un monitoraggio continuo ad alta precisione. Entrambe le opzioni si integrano perfettamente con il software ValSuite\u00ae, supportando compiti critici di validazione in contesti farmaceutici, di laboratorio e industriali.  <\/p>\n                    <\/div>\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                \r\n                <!-- Paragraph 2 -->\r\n                \r\n                                    <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/\"\r\n                        class=\"btn btn-light btn-sm mt-5\"\r\n                                                >\r\n                        Scopri di pi\u00f9                    <\/a>\r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                \r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-e0481d1 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/validation_software_07d.png');\r\n        background-repeat: no-repeat;\r\n        background-position: bottom left;\r\n        background-size: 33% auto;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-e0481d1 {\r\n            background-position: bottom left;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-e0481d1 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-e0481d1');\r\n        const content = document.getElementById('readmore-content-e0481d1');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e03664e e-con-full e-flex e-con e-parent\" data-id=\"e03664e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75a4902 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"75a4902\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-75a4902\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 bg-success\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-5 mb-5 text-white\">\r\n                        <span class=\"text-white\">Competenza globale, portata locale<\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                                    <div class=\"fs-18 fw-light mb-5 text-white lh-base wysiwyg-list\">\r\n                        <p>Nelle <a href=\"https:\/\/www.ellab.com\/it\/life-science\/\">scienze della vita<\/a>, la conformit\u00e0 non riguarda solo il rispetto dei requisiti normativi: riguarda la protezione dei pazienti, la salvaguardia della tua reputazione e la garanzia di una produzione ininterrotta. Scegliere il partner giusto fa la differenza tra reagire agli audit e anticiparli. <\/p>\n<ul>\n<li><strong>Supporto alla conformit\u00e0 end-to-end<\/strong>: un unico partner per validazione, monitoraggio e calibrazione, riducendo la complessit\u00e0 dei fornitori e aumentando la coerenza.<\/li>\n<li><strong>Competenza globale con portata locale<\/strong>: specialisti in oltre 40 paesi che garantiscono l'allineamento con le GMP regionali e i requisiti normativi.<\/li>\n<li><strong>Comprovata fiducia normativa<\/strong>: decenni di esperienza nel supporto alle ispezioni di FDA, EMA e delle autorit\u00e0 sanitarie globali.<\/li>\n<li><strong>Partnership per il ciclo di vita<\/strong>: dall'implementazione alle operazioni quotidiane, integriamo la conformit\u00e0 nei tuoi processi, non solo nella tua documentazione.<\/li>\n<li><strong>Innovazione con uno scopo<\/strong>: sviluppo continuo di hardware, software e servizi progettati per migliorare il controllo e la prevedibilit\u00e0.<\/li>\n<\/ul>\n<p>In Ellab, uniamo attrezzature, competenze e servizi per supportare l'intero ciclo di vita della conformit\u00e0. Dalla <a href=\"https:\/\/www.ellab.com\/it\/convalida\/\">validazione<\/a> e <a href=\"https:\/\/www.ellab.com\/it\/taratura\/\">calibrazione<\/a> al <a href=\"https:\/\/www.ellab.com\/it\/monitoraggio\/\">monitoraggio<\/a> continuo, ti aiutiamo a ridurre il rischio operativo, rafforzare l'integrit\u00e0 dei dati e mantenere una costante prontezza per gli audit. <\/p>\n                    <\/div>\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                \r\n                <!-- Paragraph 2 -->\r\n                \r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                \r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-75a4902 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/home_img_bg_5.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n        background-size: cover;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-75a4902 {\r\n            background-position: center center;\r\n            background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/home_img_bg_5.jpg');\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-75a4902 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-75a4902');\r\n        const content = document.getElementById('readmore-content-75a4902');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c04fe0 e-con-full e-flex e-con e-parent\" data-id=\"8c04fe0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f32c934 elementor-widget elementor-widget-two_columns_with_grid_ellab\" data-id=\"f32c934\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_with_grid_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-with-grid-f32c934\" class=\"py-4 py-md-5 px-3 px-md-0 \">\r\n    <div class=\"container position-relative my-4 my-md-5\">\r\n\r\n                <!-- End Agenda Webinar -->\r\n\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n\r\n                                <div class=\"row d-flex align-items-end mb-5\">\r\n                                        <div class=\"col-12 col-12 col-md-6\">\r\n\r\n                                                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-0 mb-5 text-primary\">\r\n                                <span class=\"text-primary\">Porta la tua validazione e conformit\u00e0 al <span class=\"text-secondary\">livello successivo<\/span><\/span>                            <\/h2>\r\n                        \r\n                                            <\/div>\r\n\r\n                    \r\n                    <div class=\"col-12 col-12 col-md-6\">\r\n                        <!-- Title -->\r\n                        \r\n                        <!-- Counter -->\r\n                        \r\n                        <!-- Description -->\r\n                                                    <div class=\"fs-24 fw-semibold text-primary mb-4\">\r\n                                <p>Dalle attrezzature ai servizi esperti, il set completo di soluzioni Ellab ti permette di gestire la conformit\u00e0 in modo efficiente e sicuro in tutte le tue operazioni.<\/p>\n                            <\/div>\r\n                        \r\n                        <!-- Custom List -->\r\n                        \r\n                        <!-- Button Right -->\r\n                        \r\n                    <\/div>\r\n                <\/div>\r\n\r\n\r\n                \r\n\r\n\r\n                                    <div class=\"row g-4 align-items-stretch mb-5\">\r\n                                                    <div class=\"col-12 col-md-6 col-lg-4 d-flex mb-2 mb-md-5\">\r\n                                <div class=\"featured-item position-relative text-white rounded-4 overflow-hidden flex-grow-1\"\r\n                                    style=\"background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-grid-1.jpg'); background-size: cover; background-position: center;\">\r\n\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/convalida\/servizi-di-convalida\/\"\r\n                                            class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                                                                                                                    aria-hidden=\"true\" tabindex=\"-1\" style=\"z-index: 3;\">\r\n                                        <\/a>\r\n                                    \r\n                                    <!-- Gradient overlay -->\r\n                                                                        <!--<div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                            style=\"\">\r\n                                        <\/div>-->\r\n                                                                        <div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                        style=\"background: linear-gradient(to right, rgb(17 45 55 \/ 53%) 100%, rgba(var(--bs-primary-rgb), 0.55) 60%, transparent 100%); z-index: 1;\">\r\n                                    <\/div>\r\n                                    \r\n                                    <div class=\"p-4 p-md-5 d-flex flex-column h-100 justify-content-start position-relative\"\r\n                                        style=\"z-index: 2;\">\r\n\r\n                                        <h3 class=\"fs-20 fw-semibold my-3 text-white\">\r\n                                            Servizi di Validazione                                        <\/h3>\r\n\r\n                                                                                    <p class=\"fs-15 text-white mb-3\">\r\n                                                Soluzioni di validazione chiavi in mano e supplementari, inclusi IQ\/OQ, qualifica delle prestazioni e supporto esperto in loco. Garantisci la conformit\u00e0 con documentazione completa e consulenza.                                             <\/p>\r\n                                        \r\n                                                                                    <a href=\"https:\/\/www.ellab.com\/it\/convalida\/servizi-di-convalida\/\"\r\n                                                class=\"text-white fw-semibold fs-15 position-relative\"\r\n                                                                                                >\r\n                                                Scopri di pi\u00f9                                            <\/a>\r\n                                        \r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12 col-md-6 col-lg-4 d-flex mb-2 mb-md-5\">\r\n                                <div class=\"featured-item position-relative text-white rounded-4 overflow-hidden flex-grow-1\"\r\n                                    style=\"background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-grid-2.jpg'); background-size: cover; background-position: center;\">\r\n\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/taratura\/servizi-di-taratura\/\"\r\n                                            class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                                                                                                                    aria-hidden=\"true\" tabindex=\"-1\" style=\"z-index: 3;\">\r\n                                        <\/a>\r\n                                    \r\n                                    <!-- Gradient overlay -->\r\n                                                                        <!--<div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                            style=\"\">\r\n                                        <\/div>-->\r\n                                                                        <div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                        style=\"background: linear-gradient(to right, rgb(17 45 55 \/ 53%) 100%, rgba(var(--bs-primary-rgb), 0.55) 60%, transparent 100%); z-index: 1;\">\r\n                                    <\/div>\r\n                                    \r\n                                    <div class=\"p-4 p-md-5 d-flex flex-column h-100 justify-content-start position-relative\"\r\n                                        style=\"z-index: 2;\">\r\n\r\n                                        <h3 class=\"fs-20 fw-semibold my-3 text-white\">\r\n                                            Servizi di Taratura                                        <\/h3>\r\n\r\n                                                                                    <p class=\"fs-15 text-white mb-3\">\r\n                                                Calibrazione accreditata in laboratorio e in loco per temperatura, pressione e umidit\u00e0. Mantieni l&#039;accuratezza e la conformit\u00e0 agli standard ISO, con il supporto di tecnici esperti.                                             <\/p>\r\n                                        \r\n                                                                                    <a href=\"https:\/\/www.ellab.com\/it\/taratura\/servizi-di-taratura\/\"\r\n                                                class=\"text-white fw-semibold fs-15 position-relative\"\r\n                                                                                                >\r\n                                                Scopri di pi\u00f9                                            <\/a>\r\n                                        \r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12 col-md-6 col-lg-4 d-flex mb-2 mb-md-5\">\r\n                                <div class=\"featured-item position-relative text-white rounded-4 overflow-hidden flex-grow-1\"\r\n                                    style=\"background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-grid-3.jpg'); background-size: cover; background-position: center;\">\r\n\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/\"\r\n                                            class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                                                                                                                    aria-hidden=\"true\" tabindex=\"-1\" style=\"z-index: 3;\">\r\n                                        <\/a>\r\n                                    \r\n                                    <!-- Gradient overlay -->\r\n                                                                        <!--<div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                            style=\"\">\r\n                                        <\/div>-->\r\n                                                                        <div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                        style=\"background: linear-gradient(to right, rgb(17 45 55 \/ 53%) 100%, rgba(var(--bs-primary-rgb), 0.55) 60%, transparent 100%); z-index: 1;\">\r\n                                    <\/div>\r\n                                    \r\n                                    <div class=\"p-4 p-md-5 d-flex flex-column h-100 justify-content-start position-relative\"\r\n                                        style=\"z-index: 2;\">\r\n\r\n                                        <h3 class=\"fs-20 fw-semibold my-3 text-white\">\r\n                                            Soluzioni a noleggio                                        <\/h3>\r\n\r\n                                                                                    <p class=\"fs-15 text-white mb-3\">\r\n                                                Opzioni di noleggio flessibili per attrezzature e accessori Ellab, ideali per progetti a breve termine o prove. Ottieni gli strumenti giusti quando ne hai bisogno, senza impegni a lungo termine.                                             <\/p>\r\n                                        \r\n                                                                                    <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/\"\r\n                                                class=\"text-white fw-semibold fs-15 position-relative\"\r\n                                                                                                >\r\n                                                Scopri di pi\u00f9                                            <\/a>\r\n                                        \r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                            <\/div>\r\n                \r\n                \r\n                \r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n\r\n<style>\r\n    #ellab-two-columns-with-grid-f32c934 {\r\n        background-image: url('');\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n        background-size: contain;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-with-grid-f32c934 {\r\n            background-position: center center;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    #ellab-two-columns-with-grid-f32c934 .container {\r\n        @media (min-width: 992px) {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n    .custom-list-wrapper .custom-dot {\r\n        width: 6px;\r\n        height: 6px;\r\n        background-color: #7BC70F;\r\n        \/* Cambia el color del punto *\/\r\n        border-radius: 50%;\r\n        margin-top: 8px;\r\n        \/* alinea con el t\u00edtulo *\/\r\n        flex-shrink: 0;\r\n    }\r\n\r\n    .agenda-col-time {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-col-topic {\r\n        flex: 0 0 60%;\r\n    }\r\n\r\n    .agenda-col-speaker {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-header,\r\n    .agenda-row {\r\n        display: flex;\r\n        align-items: center;\r\n    }\r\n\r\n    \/* LOGO GRID *\/\r\n\r\n    .logos-grid {\r\n        display: grid;\r\n        grid-template-columns: repeat(7, 1fr);\r\n        gap: 24px;\r\n        align-items: center;\r\n    }\r\n\r\n    .logo-item {\r\n        height: 100px;\r\n        \/* todos los logos ocupan la misma altura *\/\r\n        display: flex;\r\n        justify-content: center;\r\n        align-items: center;\r\n        padding: 10px;\r\n    }\r\n\r\n    .logo-item img {\r\n        max-width: 100%;\r\n        max-height: 100%;\r\n        width: auto;\r\n        height: auto;\r\n        object-fit: contain;\r\n    }\r\n\r\n    \/* Tablet *\/\r\n    @media (max-width:991px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(4, 1fr);\r\n        }\r\n    }\r\n\r\n    \/* Mobile *\/\r\n    @media (max-width:767px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(3, 1fr);\r\n            gap: 12px;\r\n        }\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        var countdownEl = document.getElementById('countdown-f32c934');\r\n        if (!countdownEl) return;\r\n\r\n        var endDate = new Date('1970-01-01 00:00:00').getTime();\r\n\r\n        function updateCountdown() {\r\n            var now = new Date().getTime();\r\n            var distance = endDate - now;\r\n            if (distance < 0) distance = 0;\r\n\r\n            var days = Math.floor(distance \/ (1000 * 60 * 60 * 24));\r\n            var hours = Math.floor((distance % (1000 * 60 * 60 * 24)) \/ (1000 * 60 * 60));\r\n            var minutes = Math.floor((distance % (1000 * 60 * 60)) \/ (1000 * 60));\r\n            var seconds = Math.floor((distance % (1000 * 60)) \/ 1000);\r\n\r\n            var values = [days, hours, minutes, seconds];\r\n\r\n            var spans = countdownEl.querySelectorAll('[data-count]');\r\n            spans.forEach(function(span, index) {\r\n                span.textContent = values[index].toString().padStart(2, '0');\r\n            });\r\n        }\r\n\r\n        updateCountdown();\r\n        setInterval(updateCountdown, 1000);\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Software di validazione ValSuite\u00ae Ottimizza validazione e calibrazione: garantisci la conformit\u00e0, risparmia tempo e ottieni il controllo completo La gestione manuale dei dati e i sistemi frammentati aumentano i rischi di conformit\u00e0 e fanno perdere tempo prezioso. ValSuite\u00ae riunisce tutti i tuoi dati di validazione e calibrazione in un&#039;unica piattaforma intuitiva, automatizzando la documentazione, garantendo [&hellip;]<\/p>\n","protected":false},"author":2456,"featured_media":0,"parent":17702,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/modules.php","meta":{"footnotes":""},"class_list":["post-18136","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Software di validazione e calibrazione ValSuite\u00ae | Ellab<\/title>\n<meta name=\"description\" content=\"EllabValSuite\u00ae \u00e8 la piattaforma software all-in-one per la validazione e la calibrazione che automatizza la reportistica, garantisce la conformit\u00e0 e fornisce dati in tempo reale per le industrie farmaceutiche, biotecnologiche e alimentari.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Software di validazione\" \/>\n<meta property=\"og:description\" content=\"EllabValSuite\u00ae \u00e8 la piattaforma software all-in-one per la validazione e la calibrazione che automatizza la reportistica, garantisce la conformit\u00e0 e fornisce dati in tempo reale per le industrie farmaceutiche, biotecnologiche e alimentari.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellab\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T14:27:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/software-di-convalida\\\/\",\"url\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/software-di-convalida\\\/\",\"name\":\"Software di validazione e calibrazione ValSuite\u00ae | Ellab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/software-di-convalida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/software-di-convalida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ellab.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/validation_icon_5.svg\",\"datePublished\":\"2026-02-23T11:28:29+00:00\",\"dateModified\":\"2026-05-14T14:27:15+00:00\",\"description\":\"EllabValSuite\u00ae \u00e8 la piattaforma software all-in-one per la validazione e la calibrazione che automatizza la reportistica, garantisce la conformit\u00e0 e fornisce dati in tempo reale per le industrie farmaceutiche, biotecnologiche e alimentari.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/software-di-convalida\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/software-di-convalida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/software-di-convalida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ellab.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/validation_icon_5.svg\",\"contentUrl\":\"https:\\\/\\\/www.ellab.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/validation_icon_5.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/software-di-convalida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Validazione\",\"item\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sistemi di convalida\",\"item\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Software di validazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/\",\"name\":\"Ellab\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Software di validazione e calibrazione ValSuite\u00ae | Ellab","description":"EllabValSuite\u00ae \u00e8 la piattaforma software all-in-one per la validazione e la calibrazione che automatizza la reportistica, garantisce la conformit\u00e0 e fornisce dati in tempo reale per le industrie farmaceutiche, biotecnologiche e alimentari.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/","og_locale":"it_IT","og_type":"article","og_title":"Software di validazione","og_description":"EllabValSuite\u00ae \u00e8 la piattaforma software all-in-one per la validazione e la calibrazione che automatizza la reportistica, garantisce la conformit\u00e0 e fornisce dati in tempo reale per le industrie farmaceutiche, biotecnologiche e alimentari.","og_url":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/","og_site_name":"Ellab","article_modified_time":"2026-05-14T14:27:15+00:00","og_image":[{"url":"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/","url":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/","name":"Software di validazione e calibrazione ValSuite\u00ae | Ellab","isPartOf":{"@id":"https:\/\/www.ellab.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/#primaryimage"},"image":{"@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg","datePublished":"2026-02-23T11:28:29+00:00","dateModified":"2026-05-14T14:27:15+00:00","description":"EllabValSuite\u00ae \u00e8 la piattaforma software all-in-one per la validazione e la calibrazione che automatizza la reportistica, garantisce la conformit\u00e0 e fornisce dati in tempo reale per le industrie farmaceutiche, biotecnologiche e alimentari.","breadcrumb":{"@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/#primaryimage","url":"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg","contentUrl":"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ellab.com\/it\/"},{"@type":"ListItem","position":2,"name":"Validazione","item":"https:\/\/www.ellab.com\/it\/convalida\/"},{"@type":"ListItem","position":3,"name":"Sistemi di convalida","item":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/"},{"@type":"ListItem","position":4,"name":"Software di validazione"}]},{"@type":"WebSite","@id":"https:\/\/www.ellab.com\/it\/#website","url":"https:\/\/www.ellab.com\/it\/","name":"Ellab","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ellab.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/18136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/users\/2456"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/comments?post=18136"}],"version-history":[{"count":2,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/18136\/revisions"}],"predecessor-version":[{"id":23480,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/18136\/revisions\/23480"}],"up":[{"embeddable":true,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/17702"}],"wp:attachment":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/media?parent=18136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}