{"id":18140,"date":"2026-02-23T12:28:29","date_gmt":"2026-02-23T11:28:29","guid":{"rendered":"https:\/\/www.ellab.com\/validazione\/sistemi-di-convalida\/noleggio-e-leasing-di-apparecchiature-per-la-validazione\/"},"modified":"2026-05-22T12:57:05","modified_gmt":"2026-05-22T10:57:05","slug":"noleggio-attrezzature-di-convalida","status":"publish","type":"page","link":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/","title":{"rendered":"Noleggio e Leasing di Apparecchiature per la Validazione"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18140\" class=\"elementor elementor-18140 elementor-8857\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b68b90 e-con-full e-flex e-con e-parent\" data-id=\"8b68b90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7fe102 elementor-widget elementor-widget-hero_ellab\" data-id=\"f7fe102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hero_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-hero-f7fe102\" class=\"d-flex align-items-center px-3 px-md-0 \" style=\"min-height: 100vh;\">\r\n    <div class=\"container\">\r\n        <div class=\"row justify-content-start\">\r\n\r\n            \r\n            <div class=\"col-12 col-md-12\">\r\n\r\n\r\n                \r\n                \r\n                                    <h1 class=\"custom-title fs-56 fw-semibold mb-5 text-secondary\">\r\n                        <span class=\"text-secondary\"><span class=\"text-white\">Noleggio e Leasing<\/span> Flessibile di Data Logger Quando Ne Hai Bisogno<\/span>                    <\/h1>\r\n                \r\n                \r\n                                    <h6 class=\"hero-subtitle fs-24 fw-semibold mb-4 text-white w-100 w-md-100\">\r\n                        Ottieni gli strumenti di validazione e il supporto di cui hai bisogno per rimanere conforme - alle tue condizioni                    <\/h6>\r\n                \r\n                                    <p class=\"fs-24 fw-light mb-4 text-white w-100 w-md-75\">\r\n                        Una soluzione intelligente per progetti di mappatura delle temperature e validazione, i servizi di leasing e noleggio di Ellab forniscono apparecchiature flessibili e pronte per la conformit\u00e0 senza investimenti di capitale iniziali. Ottieni data logger e termocoppie calibrati con integrazione perfetta con ValSuite\u00ae. Oltre al supporto di esperti per rimanere pronto per gli audit e mantenere le tue operazioni in movimento.                      <\/p>\r\n                \r\n                                                        <a href=\"#popmake-7957\"\r\n                        class=\"btn btn-sm mt-4 btn-light\"\r\n                        >\r\n                        Ottieni la tua consulenza gratuita                    <\/a>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n<style>\r\n    #ellab-hero-f7fe102 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/VALIDATION_EQUIPMENT_RENTALS_01.jpg');\r\n        background-size: cover;\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        #ellab-hero-f7fe102 {\r\n            background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/VALIDATION_EQUIPMENT_RENTALS_01.jpg');\r\n            background-position: center center;\r\n        }\r\n    }\r\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d2dd4da e-con-full e-flex e-con e-parent\" data-id=\"d2dd4da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-626be23 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"626be23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-626be23\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 \">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-primary \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-5 text-primary\">\r\n                        <span class=\"text-primary\"><span class=\"text-secondary\">Noleggio e Leasing<\/span> Flessibile di Data Logger per Ambienti Regolamentati<\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                                    <div class=\"video-cover position-relative mt-5 mb-5 mb-md-0\" style=\"display:inline-block;\">\r\n\r\n                        <!-- Clickable cover -->\r\n                        <div class=\"video-cover-trigger\"\r\n                            data-video-id=\"\"\r\n                            style=\"cursor:pointer; display:inline-block; position:relative;\">\r\n\r\n                            <!-- Cover image -->\r\n                            \r\n                            <!-- Play icon -->\r\n                                                            <span class=\"play-icon-wrap\">\r\n                                                                    <\/span>\r\n                            \r\n                        <\/div>\r\n\r\n                        <!-- Iframe container (hidden by default) -->\r\n                        <div class=\"video-embed-container\"\r\n                            style=\"display:none; position:absolute; top:0; left:0; width:100%; height:100%; border-radius:1rem; overflow:hidden; z-index:10;\">\r\n                        <\/div>\r\n                    <\/div>\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-primary\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                                    <h6 class=\"fs-24 fw-semibold  mb-4 text-primary\">\r\n                        I team di validazione devono gestire scadenze strette, ritardi negli approvvigionamenti e picchi stagionali di mappatura - la nostra flotta di noleggio globale rimuove questi ostacoli.                    <\/h6>\r\n                \r\n                <!-- Right Paragraph -->\r\n                                    <div class=\"fs-18 fw-light mb-5 text-primary lh-base wysiwyg-list\">\r\n                        <p>Ellab fornisce logger e accessori pre-calibrati su richiesta, completamente supportati da esperti di conformit\u00e0, cos\u00ec puoi mantenere la preparazione agli audit senza investimenti di capitale iniziali. Con i noleggi di apparecchiature Ellab, ci occupiamo noi della conformit\u00e0 cos\u00ec tu puoi concentrarti sulla scienza. <\/p>\n<p>Tutti i noleggi si integrano con <strong>ValSuite\u00ae<\/strong>, la nostra piattaforma conforme a 21 CFR Part 11 per acquisizione, revisione e reportistica sicura dei dati.<\/p>\n                    <\/div>\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                \r\n                <!-- Paragraph 2 -->\r\n                \r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                \r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-626be23 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/temperature_validation_06.png');\r\n        background-repeat: no-repeat;\r\n        background-position: bottom left;\r\n        background-size: 23% auto;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-626be23 {\r\n            background-position: bottom left;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-626be23 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-626be23');\r\n        const content = document.getElementById('readmore-content-626be23');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07c9826 e-con-full e-flex e-con e-parent\" data-id=\"07c9826\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4933e80 elementor-widget elementor-widget-one_column_with_grid_ellab\" data-id=\"4933e80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"one_column_with_grid_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\r\n<section id=\"ellab-one-column-4933e80\"\r\n    class=\"py-4 py-lg-5 \">\r\n\r\n    <div class=\"container my-4 my-lg-5 \">\r\n        <div class=\"row text-center justify-content-center\">\r\n\r\n            \r\n            \r\n            \r\n                        \r\n                            <!-- Subtitle Top -->\r\n                                    <div class=\"col-12 mt-5\">\r\n                        <h5 class=\"fs-36 fw-semibold text-primary mb-5\">\r\n                            Apparecchiature per la Validazione per Tutte le Tue Esigenze                        <\/h5>\r\n                    <\/div>\r\n                \r\n\r\n                <!-- ==================== Grid Applications ==================== -->\r\n                <div class=\"col-12 col-md-10\">\r\n                                        <div class=\"row row-cols-2 row-cols-sm-2 row-cols-lg-4 gx-4 gy-0 g-md-5 justify-content-center\">\r\n                                                    <div class=\"col d-flex justify-content-center\">\r\n                                <div class=\"align-items-center text-center\">\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/life-science\/strumentazione-per-processi-produttivi\/liofilizzatori\/\"  class=\"text-decoration-none text-reset d-block\">\r\n                                        \r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-isolator.png\"\r\n                                                alt=\"Liofilizzatori\"\r\n                                                class=\"img-fluid mb-3 rounded-circle\"\r\n                                                style=\"max-width: 140px; width: 140px; height: 140px; object-fit: cover;\" \/>\r\n                                        \r\n                                                                                    <h6 class=\"fs-20 fw-semibold mb-2 text-primary\">Liofilizzatori<\/h6>\r\n                                        \r\n                                        \r\n                                                                                <\/a>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col d-flex justify-content-center\">\r\n                                <div class=\"align-items-center text-center\">\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/life-science\/strumentazione-di-stoccaggio-e-di-laboratorio\/congelatori-e-frigoriferi\/\"  class=\"text-decoration-none text-reset d-block\">\r\n                                        \r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-freezers.png\"\r\n                                                alt=\"Congelatori e Frigoriferi \"\r\n                                                class=\"img-fluid mb-3 rounded-circle\"\r\n                                                style=\"max-width: 140px; width: 140px; height: 140px; object-fit: cover;\" \/>\r\n                                        \r\n                                                                                    <h6 class=\"fs-20 fw-semibold mb-2 text-primary\">Congelatori e Frigoriferi <\/h6>\r\n                                        \r\n                                        \r\n                                                                                <\/a>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col d-flex justify-content-center\">\r\n                                <div class=\"align-items-center text-center\">\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/life-science\/strumentazione-di-stoccaggio-e-di-laboratorio\/camere-fredde-walk-in\/\"  class=\"text-decoration-none text-reset d-block\">\r\n                                        \r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-rach-in.png\"\r\n                                                alt=\"Walk-In e Reach-In\"\r\n                                                class=\"img-fluid mb-3 rounded-circle\"\r\n                                                style=\"max-width: 140px; width: 140px; height: 140px; object-fit: cover;\" \/>\r\n                                        \r\n                                                                                    <h6 class=\"fs-20 fw-semibold mb-2 text-primary\">Walk-In e Reach-In<\/h6>\r\n                                        \r\n                                        \r\n                                                                                <\/a>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col d-flex justify-content-center\">\r\n                                <div class=\"align-items-center text-center\">\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/life-science\/strumentazione-di-stoccaggio-e-di-laboratorio\/incubatori\/\"  class=\"text-decoration-none text-reset d-block\">\r\n                                        \r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-incubator.png\"\r\n                                                alt=\"Incubatori\"\r\n                                                class=\"img-fluid mb-3 rounded-circle\"\r\n                                                style=\"max-width: 140px; width: 140px; height: 140px; object-fit: cover;\" \/>\r\n                                        \r\n                                                                                    <h6 class=\"fs-20 fw-semibold mb-2 text-primary\">Incubatori<\/h6>\r\n                                        \r\n                                        \r\n                                                                                <\/a>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col d-flex justify-content-center\">\r\n                                <div class=\"align-items-center text-center\">\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/life-science\/camere-climatiche\/camere-di-stabilita\/\"  class=\"text-decoration-none text-reset d-block\">\r\n                                        \r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-stability-chamber.png\"\r\n                                                alt=\"Camere di Stabilit\u00e0\"\r\n                                                class=\"img-fluid mb-3 rounded-circle\"\r\n                                                style=\"max-width: 140px; width: 140px; height: 140px; object-fit: cover;\" \/>\r\n                                        \r\n                                                                                    <h6 class=\"fs-20 fw-semibold mb-2 text-primary\">Camere di Stabilit\u00e0<\/h6>\r\n                                        \r\n                                        \r\n                                                                                <\/a>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col d-flex justify-content-center\">\r\n                                <div class=\"align-items-center text-center\">\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/life-science\/sterilizzazione-decontaminazione\/sterilizzazione-a-vapore\/\"  class=\"text-decoration-none text-reset d-block\">\r\n                                        \r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-steam-sterilization.png\"\r\n                                                alt=\"Sterilizzazione a Vapore\"\r\n                                                class=\"img-fluid mb-3 rounded-circle\"\r\n                                                style=\"max-width: 140px; width: 140px; height: 140px; object-fit: cover;\" \/>\r\n                                        \r\n                                                                                    <h6 class=\"fs-20 fw-semibold mb-2 text-primary\">Sterilizzazione a Vapore<\/h6>\r\n                                        \r\n                                        \r\n                                                                                <\/a>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col d-flex justify-content-center\">\r\n                                <div class=\"align-items-center text-center\">\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/life-science\/sterilizzazione-decontaminazione\/tunnel-e-forni-di-depirogenazione\/\"  class=\"text-decoration-none text-reset d-block\">\r\n                                        \r\n                                                                                    <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-depyrogenation.png\"\r\n                                                alt=\"Depirogenazione e Forni \"\r\n                                                class=\"img-fluid mb-3 rounded-circle\"\r\n                                                style=\"max-width: 140px; width: 140px; height: 140px; object-fit: cover;\" \/>\r\n                                        \r\n                                                                                    <h6 class=\"fs-20 fw-semibold mb-2 text-primary\">Depirogenazione e Forni <\/h6>\r\n                                        \r\n                                        \r\n                                                                                <\/a>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n\r\n                <!-- Subtitle Bottom -->\r\n                \r\n            \r\n\r\n            <!-- ==================== Button All Applications ==================== -->\r\n            \r\n            <!-- ==================== Video ==================== -->\r\n\r\n            \r\n            \r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n<style>\r\n    #ellab-one-column-4933e80 {\r\n        background-image: url('');\r\n        background-size: auto;\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n    }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-one-column-4933e80 {\r\n            background-position: center center;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f66091 e-con-full e-flex e-con e-parent\" data-id=\"2f66091\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca4ad18 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"ca4ad18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-ca4ad18\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 bg-success\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-5 mb-5 text-white\">\r\n                        <span class=\"text-white\">Inizia Oggi la Conversazione sul Noleggio o Leasing<\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                                    <h6 class=\"fs-24 fw-semibold mb-4 text-white\">\r\n                        Che tu abbia bisogno di apparecchiature a noleggio a breve termine o opzioni di leasing a lungo termine, ti metteremo rapidamente in funzione.                    <\/h6>\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                \r\n                <!-- Paragraph 2 -->\r\n                \r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                <iframe class=\"pardotform\" src=\"https:\/\/www2.ellab.com\/l\/971953\/2022-08-30\/9hwy\" width=\"100%\" height=\"680\" frameborder=\"0\" pardot-form-name=\"IT-Contact-Ellab\"><\/iframe>\r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-ca4ad18 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/img_form_module-2.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n        background-size: cover;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-ca4ad18 {\r\n            background-position: center center;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-ca4ad18 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-ca4ad18');\r\n        const content = document.getElementById('readmore-content-ca4ad18');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54530fb e-con-full e-flex e-con e-parent\" data-id=\"54530fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89acab8 elementor-widget elementor-widget-testimonial_ellab\" data-id=\"89acab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-testimonial-89acab8\" class=\"section-carousel testimonial-carousel py-4 py-lg-5 px-3 px-md-0\" aria-label=\"Testimonials Carousel\">\r\n    <div class=\"container my-4 my-lg-5\">\r\n        <div class=\"row justify-content-center\">\r\n            <div class=\"col-12 col-md-10 mx-auto\">\r\n                <div class=\"row justify-content-center\">\r\n                    <div class=\"col-12\">\r\n\r\n                        \r\n                                                    <h3 class=\"custom-title fs-36 fw-semibold mb-5 text-center text-primary\">\r\n                                <span class=\"text-primary\"><\/span>                            <\/h3>\r\n                        \r\n\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                                    <div class=\"splide\" id=\"testimonial-splide-89acab8\">\r\n                        <div class=\"splide__track\">\r\n                            <ul class=\"splide__list\">\r\n                                                                    <li class=\"splide__slide\">\r\n                                        <div class=\"bg-gradient-light p-5 rounded-4\">\r\n                                            <div class=\"row align-items-start\">\r\n                                                <div class=\"col-auto col-md-1 d-flex justify-content-center justify-content-md-start\">\r\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/quote.svg\"\r\n                                                            alt=\"Quote Mark\"\r\n                                                            class=\"quote-mark\" \/>\r\n                                                                                                    <\/div>\r\n                                                <div class=\"col-12 col-md-11\">\r\n                                                    <blockquote class=\"flex-grow-1 ms-0 ms-md-5 mb-0 mb-md-4\">\r\n                                                        <div class=\"fs-20 fst-italic mb-5 text-start\">\r\n                                                            <p>La nostra struttura utilizza i data logger Ellab da anni. Abbiamo circa 200 unit\u00e0 e siamo molto soddisfatti. I rappresentanti di zona sono fantastici e sempre pronti ad aiutare. Un ottimo prodotto su cui investire. Inoltre, \u00e8 conforme alla normativa Part 11!    <\/p>\n                                                        <\/div>\r\n                                                    <\/blockquote>\r\n                                                <\/div>\r\n                                                <footer class=\"text-center py-md-4 py-4\">\r\n                                                    <div class=\"fs-15 text-dark fw-bold\">Don Narron<\/div>\r\n                                                    <div class=\"fs-15 text-secondary fw-bold\">GSK<\/div>\r\n                                                    <div class=\"fs-13 text-muted fw-bold\"><\/div>\r\n                                                    <div class=\"fs-13 text-muted\"><\/div>\r\n                                                <\/footer>\r\n                                            <\/div>\r\n\r\n                                        <\/div>\r\n                                    <\/li>\r\n                                                            <\/ul>\r\n                        <\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n\r\n<style>\r\n    #ellab-testimonial-89acab8 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/home_img_bg_6.png');\r\n        background-size: contain;\r\n        background-repeat: no-repeat;\r\n        background-position: center left;\r\n    }\r\n\r\n    @media (max-width: 991px) {\r\n        #ellab-testimonial-89acab8 {\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    #testimonial-splide-89acab8 .splide__pagination__page {\r\n        background: #d3d3d3 !important;\r\n        border: none !important;\r\n        opacity: 1 !important;\r\n        width: 6px !important;\r\n        height: 6px !important;\r\n        margin: 0 6px !important;\r\n    }\r\n\r\n    #testimonial-splide-89acab8 .splide__pagination__page.is-active {\r\n        background: var(--bs-primary) !important;\r\n        transform: scale(1.8) !important;\r\n    }\r\n\r\n    #testimonial-splide-89acab8 .bg-gradient-light {\r\n        background: linear-gradient(to right,\r\n                rgba(241, 242, 244, 0.6) 0%,\r\n                rgba(241, 242, 244, 0.85) 40%);\r\n    }\r\n\r\n\r\n    .elementor .quote-mark {\r\n        width: 200px;\r\n        max-width: none;\r\n        height: auto;\r\n        margin-bottom: 0;\r\n        \/* o lo que necesites *\/\r\n    }\r\n\r\n    @media (max-width: 1024px) {\r\n        .elementor .quote-mark {\r\n            width: 120px;\r\n            margin-bottom: 30px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767.98px) {\r\n        .elementor .quote-mark {\r\n            width: 60px;\r\n            margin-bottom: 30px;\r\n        }\r\n    }\r\n<\/style>\r\n\r\n\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        if (typeof Splide !== 'undefined') {\r\n            new Splide('#testimonial-splide-89acab8', {\r\n                type: 'loop',\r\n                perPage: 1,\r\n                arrows: false,\r\n                pagination: true,\r\n                autoplay: true,\r\n                interval: 5000,\r\n                pauseOnHover: true,\r\n                classes: {\r\n                    pagination: 'splide__pagination mt-4 text-center',\r\n                    page: 'splide__pagination__page',\r\n                },\r\n            }).mount();\r\n        }\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2aa3b7b e-con-full e-flex e-con e-parent\" data-id=\"2aa3b7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f688a6 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"8f688a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-8f688a6\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 bg-primary\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-5 mb-5 text-white\">\r\n                        <span class=\"text-white\"><span class=\"text-secondary\">Perch\u00e9 i Leader del Settore<\/span> Scelgono il Noleggio e Leasing di Data Logger Ellab<\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                                    <div class=\"fs-18 fw-light mb-5 text-white lh-base wysiwyg-list\">\r\n                        <p>Quando si tratta di validazione e qualificazione delle apparecchiature, flessibilit\u00e0 e affidabilit\u00e0 sono fondamentali. Le opzioni di noleggio e leasing di Ellab ti forniscono data logger calibrati di alta qualit\u00e0 su richiesta - aiutandoti a rispettare le scadenze dei progetti, mantenere la conformit\u00e0 e ottimizzare i costi senza sacrificare precisione o supporto. <\/p>\n                    <\/div>\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                                                        <h6 class=\"fs-36 fw-semibold mt-5 mb-4 text-white\">\r\n                        Noleggio vs Leasing di Apparecchiature                    <\/h6>\r\n                \r\n                <!-- Paragraph 2 -->\r\n                                    <span class=\"fs-18 fs-light mb-5 text-white lh-base\"><p>A seconda delle tue esigenze operative e finanziarie, ci adattiamo per garantire massima operativit\u00e0 e prevedibilit\u00e0:<\/p>\n<\/span>\r\n                \r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                                    <div class=\"row g-4 \">\r\n                                            <\/div>\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                                    <div class=\"row g-4 mb-4 mt-4\">\r\n                        <div class=\"col-6\">\r\n                                                            <h5 class=\"fs-24 fw-semibold text-white\">Noleggio su Richiesta<\/h5>\r\n                                                                                        <div class=\"fs-18 fw-light text-white\"><p>Quando la domanda \u00e8 temporanea, imprevedibile o critica in termini di tempo.<\/p>\n<ul>\n<li>Perfetto per progetti, picchi o scadenze urgenti.<\/li>\n<li>Apparecchiature calibrate e pronte all'uso.<\/li>\n<li>Nessun investimento iniziale.<\/li>\n<\/ul>\n<\/div>\r\n                                                    <\/div>\r\n\r\n                        <div class=\"col-6\">\r\n                                                            <h5 class=\"fs-24 fw-semibold text-white\">Leasing a 36 Mesi<\/h5>\r\n                                                                                        <div class=\"fs-18 fw-light text-white\"><p>Quando hai bisogno di stabilit\u00e0 senza vincolare capitale.<\/p>\n<ul>\n<li>Disponibilit\u00e0 a lungo termine con controllo del budget.<\/li>\n<li>Opzione di aggiornamento nel tempo.<\/li>\n<li>Costo mensile fisso.<\/li>\n<\/ul>\n<\/div>\r\n                                                    <\/div>\r\n                    <\/div>\r\n                \r\n\r\n                                    <div class=\"row pt-5\">\r\n                        <div class=\"col-12\">\r\n                            <div class=\"container bg-blur-primary rounded-4 p-4 p-md-5\">\r\n                                <ul class=\"list-unstyled\">\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Veloce e Pronto all&#039;Uso: Apparecchiature completamente calibrate, consegnate immediatamente senza investimento di capitale.                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Fiducia Normativa: Calibrazioni ISO 17025 e software conforme a Part 11 per la conformit\u00e0 GMP\/FDA.                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Flessibile ed Economico: Noleggia solo ci\u00f2 di cui hai bisogno, senza impegni a lungo termine.                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Integrazione Perfetta: Acquisizione automatica dei dati con ValSuite\u00ae.                                            <\/span>\r\n                                        <\/li>\r\n                                                                            <li class=\"d-flex align-items-center mb-4\">\r\n                                            <span class=\"bg-secondary rounded-circle me-4\" style=\"width:8px; height:8px; flex-shrink:0;\"><\/span>\r\n                                            <span class=\"text-white\">\r\n                                                Supporto Esperto: Specialisti della validazione globali ti guidano in ogni fase.                                            <\/span>\r\n                                        <\/li>\r\n                                                                    <\/ul>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                \r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-8f688a6 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/VALIDATION_EQUIPMENT_RENTALS_06.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: bottom left;\r\n        background-size: 60% auto;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-8f688a6 {\r\n            background-position: bottom left;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-8f688a6 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-8f688a6');\r\n        const content = document.getElementById('readmore-content-8f688a6');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6139e63 e-con-full e-flex e-con e-parent\" data-id=\"6139e63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2e06ac elementor-widget elementor-widget-two_columns_with_grid_ellab\" data-id=\"a2e06ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_with_grid_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-with-grid-a2e06ac\" class=\"py-4 py-md-5 px-3 px-md-0 \">\r\n    <div class=\"container position-relative my-4 my-md-5\">\r\n\r\n                <!-- End Agenda Webinar -->\r\n\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n\r\n                                <div class=\"row d-flex align-items-start mb-5\">\r\n                                        <div class=\"col-12 col-12 col-md-8\">\r\n\r\n                                                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-0 mb-5 text-secondary\">\r\n                                <span class=\"text-secondary\">Apparecchiature per la Validazione Calibrate e Pronte all'Uso \u2013 <span class=\"text-primary\">Tutto in Una Scatola<\/span><\/span>                            <\/h2>\r\n                        \r\n                                                    <div class=\"fs-24 fw-semibold text-primary mt-5\">\r\n                                <p><a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/datalogger-senza-fili\/\">Data Logger Wireless TrackSense\u00ae<\/a>: Misurano temperatura, umidit\u00e0, CO\u2082 e altro. Ideali per lo stoccaggio a temperatura ultra-bassa e la mappatura di camere bianche. <\/p>\n<p><a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/sistema-di-convalida-cablato\/\">Sistema a Termocoppia E-Val\u2122 Pro Plus<\/a>: Sistema ad alta capacit\u00e0 di canali e precisione, ideale per autoclavi, SIP e camere ad alta temperatura.<\/p>\n                            <\/div>\r\n                                            <\/div>\r\n\r\n                    \r\n                    <div class=\"col-12 col-12 col-md-4\">\r\n                        <!-- Title -->\r\n                        \r\n                        <!-- Counter -->\r\n                        \r\n                        <!-- Description -->\r\n                        \r\n                        <!-- Custom List -->\r\n                        \r\n                        <!-- Button Right -->\r\n                        \r\n                    <\/div>\r\n                <\/div>\r\n\r\n\r\n                \r\n\r\n\r\n                \r\n                \r\n                \r\n                                    <div class=\"row mb-5\">\r\n                        <div class=\"col-12\">\r\n                            <div class=\"container bg-blur-light rounded-4 p-4 p-md-5\">\r\n                                <div class=\"row\">\r\n                                                                            <div class=\"col-md-4\">\r\n                                            <ul class=\"list-unstyled\">\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Temperatura: da \u201390 \u00b0C a +400 \u00b0C                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Umidit\u00e0 relativa                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Pressione                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                            <\/ul>\r\n                                        <\/div>\r\n                                                                            <div class=\"col-md-4\">\r\n                                            <ul class=\"list-unstyled\">\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            CO\u2082                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Conduttivit\u00e0                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Vuoto                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                            <\/ul>\r\n                                        <\/div>\r\n                                                                            <div class=\"col-md-4\">\r\n                                            <ul class=\"list-unstyled\">\r\n                                                                                                    <li class=\"d-flex align-items-center mb-4\">\r\n                                                        <!-- SVG Icon -->\r\n                                                                                                                    <span class=\"me-4 flex-shrink-0\" style=\"width:24px; height:24px;\">\r\n                                                                <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/09\/validation_icon_5.svg\" alt=\"icon\" style=\"width:100%; height:100%;\">\r\n                                                            <\/span>\r\n                                                        \r\n                                                        <!-- Texto del item -->\r\n                                                        <span class=\"text-primary\">\r\n                                                            Dati in Tempo Reale (Disponibili con Modulo Sky)                                                        <\/span>\r\n                                                    <\/li>\r\n                                                                                            <\/ul>\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                \r\n\r\n                \r\n                    <div class=\"col-12 col-md-8 text-start\">\r\n\r\n                                                    <div class=\"fs-36 fw-semibold mb-4 text-primary\">\r\n                                Software ValSuite\u00ae \u2013 Conformit\u00e0 e Reportistica Unificate                            <\/div>\r\n                        \r\n                        \r\n                                                    <div class=\"fs-18 fw-light text-primary\">\r\n                                <p>Il <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/\">software di validazione di Ellab<\/a> semplifica ogni fase del tuo studio:<\/p>\n<ul>\n<li>Piena conformit\u00e0 a <strong>21 CFR Part 11 \/ EU Annex 11<\/strong><\/li>\n<li>Acquisizione automatica dei dati e modelli di studio<\/li>\n<li>Report unificati su piattaforme cablate\/wireless<\/li>\n<li>Firme elettroniche e controlli di accesso<\/li>\n<\/ul>\n                            <\/div>\r\n                        \r\n                    <\/div>\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n\r\n<style>\r\n    #ellab-two-columns-with-grid-a2e06ac {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/VALIDATION_EQUIPMENT_RENTALS_07b.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: center right;\r\n        background-size: 49% auto;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-with-grid-a2e06ac {\r\n            background-position: center right;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    #ellab-two-columns-with-grid-a2e06ac .container {\r\n        @media (min-width: 992px) {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n    .custom-list-wrapper .custom-dot {\r\n        width: 6px;\r\n        height: 6px;\r\n        background-color: #7BC70F;\r\n        \/* Cambia el color del punto *\/\r\n        border-radius: 50%;\r\n        margin-top: 8px;\r\n        \/* alinea con el t\u00edtulo *\/\r\n        flex-shrink: 0;\r\n    }\r\n\r\n    .agenda-col-time {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-col-topic {\r\n        flex: 0 0 60%;\r\n    }\r\n\r\n    .agenda-col-speaker {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-header,\r\n    .agenda-row {\r\n        display: flex;\r\n        align-items: center;\r\n    }\r\n\r\n    \/* LOGO GRID *\/\r\n\r\n    .logos-grid {\r\n        display: grid;\r\n        grid-template-columns: repeat(7, 1fr);\r\n        gap: 24px;\r\n        align-items: center;\r\n    }\r\n\r\n    .logo-item {\r\n        height: 100px;\r\n        \/* todos los logos ocupan la misma altura *\/\r\n        display: flex;\r\n        justify-content: center;\r\n        align-items: center;\r\n        padding: 10px;\r\n    }\r\n\r\n    .logo-item img {\r\n        max-width: 100%;\r\n        max-height: 100%;\r\n        width: auto;\r\n        height: auto;\r\n        object-fit: contain;\r\n    }\r\n\r\n    \/* Tablet *\/\r\n    @media (max-width:991px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(4, 1fr);\r\n        }\r\n    }\r\n\r\n    \/* Mobile *\/\r\n    @media (max-width:767px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(3, 1fr);\r\n            gap: 12px;\r\n        }\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        var countdownEl = document.getElementById('countdown-a2e06ac');\r\n        if (!countdownEl) return;\r\n\r\n        var endDate = new Date('1970-01-01 00:00:00').getTime();\r\n\r\n        function updateCountdown() {\r\n            var now = new Date().getTime();\r\n            var distance = endDate - now;\r\n            if (distance < 0) distance = 0;\r\n\r\n            var days = Math.floor(distance \/ (1000 * 60 * 60 * 24));\r\n            var hours = Math.floor((distance % (1000 * 60 * 60 * 24)) \/ (1000 * 60 * 60));\r\n            var minutes = Math.floor((distance % (1000 * 60 * 60)) \/ (1000 * 60));\r\n            var seconds = Math.floor((distance % (1000 * 60)) \/ 1000);\r\n\r\n            var values = [days, hours, minutes, seconds];\r\n\r\n            var spans = countdownEl.querySelectorAll('[data-count]');\r\n            spans.forEach(function(span, index) {\r\n                span.textContent = values[index].toString().padStart(2, '0');\r\n            });\r\n        }\r\n\r\n        updateCountdown();\r\n        setInterval(updateCountdown, 1000);\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1a3b47 e-con-full e-flex e-con e-parent\" data-id=\"d1a3b47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0481d1 elementor-widget elementor-widget-two_columns_ellab\" data-id=\"e0481d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-e0481d1\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 bg-primary\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        \r\n\r\n        <div class=\"row align-items-start\">\r\n\r\n            <!-- \r\n            Left Column\r\n            -----------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white \">\r\n                <!-- Section Title -->\r\n                \r\n                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-15 text-white\">\r\n                        <span class=\"text-white\">Pianifica <span class=\"text-secondary\">con Facilit\u00e0<\/span> la Rimappatura Stagionale o gli Studi Basati su Progetti<\/span>                    <\/h2>\r\n\r\n                \r\n\r\n                <!-- Left Subtitle -->\r\n                \r\n                <!-- Left Paragraph -->\r\n                \r\n                <!-- Left List -->\r\n                \r\n\r\n                <!-- Left Button -->\r\n                \r\n\r\n\r\n                <!-- Video Cover -->\r\n                                    <div class=\"video-cover position-relative mt-5 mb-5 mb-md-0\" style=\"display:inline-block;\">\r\n\r\n                        <!-- Clickable cover -->\r\n                        <div class=\"video-cover-trigger\"\r\n                            data-video-id=\"\"\r\n                            style=\"cursor:pointer; display:inline-block; position:relative;\">\r\n\r\n                            <!-- Cover image -->\r\n                            \r\n                            <!-- Play icon -->\r\n                                                            <span class=\"play-icon-wrap\">\r\n                                                                    <\/span>\r\n                            \r\n                        <\/div>\r\n\r\n                        <!-- Iframe container (hidden by default) -->\r\n                        <div class=\"video-embed-container\"\r\n                            style=\"display:none; position:absolute; top:0; left:0; width:100%; height:100%; border-radius:1rem; overflow:hidden; z-index:10;\">\r\n                        <\/div>\r\n                    <\/div>\r\n                \r\n\r\n                \r\n\r\n\r\n            <\/div>\r\n\r\n            <!-- \r\n            Right Column\r\n            ------------\r\n            -->\r\n\r\n            <div class=\"col-12 col-md-6 text-white\">\r\n\r\n                \r\n                \r\n\r\n\r\n                \r\n                <!-- Subtitle Right -->\r\n                \r\n                <!-- Right Paragraph -->\r\n                                    <div class=\"fs-18 fw-light mb-5 text-white lh-base wysiwyg-list\">\r\n                        <p>I requisiti di mappatura delle temperature spesso aumentano stagionalmente, specialmente in magazzini, celle frigorifere e veicoli di trasporto. Piuttosto che acquistare apparecchiature che rimangono inutilizzate, il noleggio di apparecchiature per la validazione ti consente di rimanere conforme ottimizzando le risorse. <\/p>\n<p>I nostri kit a noleggio vengono <strong>consegnati pre-calibrati e configurati<\/strong>, con supporto remoto se necessario.<\/p>\n                    <\/div>\r\n                \r\n\r\n                \r\n                <!-- Right Title -->\r\n                \r\n                <!-- Paragraph 2 -->\r\n                \r\n                                    <a href=\"https:\/\/www.ellab.com\/it\/convalida\/servizi-di-convalida\/servizi-di-mappatura-della-temperatura\/\"\r\n                        class=\"btn btn-light btn-sm mt-5\"\r\n                                                >\r\n                        Scopri i Nostri Servizi di Mappatura                    <\/a>\r\n                \r\n                \r\n                <!-- Bottom Cards -->\r\n                                    <div class=\"row g-4 my-4 my-md-5\">\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-primary p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom me-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-icon-1.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Aumenta rapidamente la capacit\u00e0 per le finestre di riqualificazione primaverili\/estive.<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-primary p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom me-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-icon-2.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Rimani agile quando affronti audit non pianificati o sostituzioni di apparecchiature.<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12\">\r\n                                <div class=\"rounded-3 bg-blur-primary p-4 p-md-5 d-flex flex-column flex-md-row align-items-start gap-4 gap-md-5\">\r\n                                    <!-- Icon -->\r\n                                                                            <div class=\"card-icon-bottom me-4\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-icon-3.svg\" alt=\"\">\r\n                                        <\/div>\r\n                                    \r\n                                    <!-- Card Content -->\r\n                                    <div>\r\n                                                                                                                            <div class=\"fs-16 mb-0 lh-base\"><p>Risparmia sui costi per aree mappate raramente (ad es. stoccaggio a basso utilizzo o congelatori legacy).<\/p>\n<\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                            <\/div>\r\n                \r\n\r\n                \r\n                <!-- Fila de dos columnas -->\r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n\r\n                \r\n\r\n                <!-- Iframe para cargar el formulario -->\r\n                \r\n                <!-- Form deshabilitado, se usar\u00e1 un iframe para cargar el formulario -->\r\n                \r\n                \r\n\r\n\r\n\r\n\r\n            <\/div>\r\n\r\n            \r\n\r\n            \r\n\r\n            \r\n\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n    <!---------------\r\n    SECTION READ MORE\r\n    -----------------\r\n    -->\r\n\r\n    \r\n    <!-- \r\n    Section Services List\r\n    ---------------------\r\n    -->\r\n\r\n    \r\n\r\n    \r\n<\/section>\r\n\r\n\r\n<style>\r\n    \/* ===========================\r\n       BACKGROUND SECTION\r\n       =========================== *\/\r\n    #ellab-two-columns-e0481d1 {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/VALIDATION_EQUIPMENT_RENTALS_08.jpg');\r\n        background-repeat: no-repeat;\r\n        background-position: bottom left;\r\n        background-size: 55% auto;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-e0481d1 {\r\n            background-position: bottom left;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    @media (min-width: 992px) {\r\n        #ellab-two-columns-e0481d1 .container {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       MATRIX SECTION\r\n       =========================== *\/\r\n    .matrix-icon svg {\r\n        max-height: 30px;\r\n        width: auto;\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .matrix-icon svg {\r\n            max-height: 20px;\r\n        }\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n        .header-text-vertical {\r\n            writing-mode: vertical-rl;\r\n            transform: rotate(180deg);\r\n            white-space: nowrap;\r\n            height: 100px;\r\n            line-height: 1.2;\r\n        }\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       LEFT AND RIGHT PARAGRAPH - LIST\r\n       =========================== *\/\r\n    .wysiwyg-list ul {\r\n        list-style: none;\r\n        padding-left: 1.2rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li {\r\n        position: relative;\r\n        margin-bottom: 0.6rem;\r\n    }\r\n\r\n    .wysiwyg-list ul li::before {\r\n        content: \"\";\r\n        position: absolute;\r\n        left: -1.2rem;\r\n        top: 0.55rem;\r\n        width: 6px;\r\n        height: 6px;\r\n        \/*background-color: #A01966;*\/\r\n        background-color: #00004b;\r\n        border-radius: 50%;\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       CUSTOM FORM\r\n       =========================== \r\n    .custom-form .form-control,\r\n    .custom-form .form-select {\r\n        background-color: #ffffff;\r\n        border: 1px solid #ced4da;\r\n        padding: 16px 20px;\r\n        border-radius: 8px;\r\n        color: #00004b !important;\r\n    }\r\n\r\n    .custom-form .form-control:focus,\r\n    .custom-form .form-select:focus {\r\n        border-color: transparent;\r\n        box-shadow: none;\r\n    }\r\n\r\n    .custom-form .form-select {\r\n        -webkit-appearance: none;\r\n        -moz-appearance: none;\r\n        appearance: none;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper {\r\n        position: relative;\r\n    }\r\n\r\n    .custom-form .form-select-wrapper::after {\r\n        content: '';\r\n        position: absolute;\r\n        top: 50%;\r\n        right: 12px;\r\n        width: 10px;\r\n        height: 10px;\r\n        background-color: #198754;\r\n        clip-path: polygon(100% 0%, 0 0%, 50% 100%);\r\n        transform: translateY(-50%);\r\n        pointer-events: none;\r\n    }\r\n\r\n    .custom-form .agreement-text {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 16px;\r\n    }\r\n\r\n    .custom-form .agreement-text svg {\r\n        flex-shrink: 0;\r\n        width: 24px;\r\n        height: 24px;\r\n        margin-top: 2px;\r\n    }\r\n    *\/\r\n\r\n\r\n\r\n    \/* ===========================\r\n       POLICY SECTION\r\n       =========================== *\/\r\n    .policy-section2-item .bullet-text {\r\n        position: relative;\r\n        padding-left: 1rem;\r\n    }\r\n\r\n    .policy-section2-item .bullet-text::before {\r\n        content: '';\r\n        position: absolute;\r\n        left: 0;\r\n        top: 0.5em;\r\n        width: 6px;\r\n        height: 6px;\r\n        border-radius: 50%;\r\n        background-color: var(--bs-secondary);\r\n    }\r\n\r\n\r\n    \/* ===========================\r\n       IMAGES SECTION\r\n       =========================== *\/\r\n\r\n    \/* Desktop baseline behavior *\/\r\n    .left-image-block,\r\n    .right-image-block {\r\n        position: relative;\r\n        display: inline-block;\r\n    }\r\n\r\n    .left-image,\r\n    .right-image,\r\n    .center-image {\r\n        width: 100%;\r\n        height: auto;\r\n        display: block;\r\n    }\r\n\r\n    \/* Caption always inside container *\/\r\n    .image-caption {\r\n        position: absolute;\r\n        bottom: 8px;\r\n        max-width: 100%;\r\n        padding-left: 8px;\r\n    }\r\n\r\n    \/* Caption align sides *\/\r\n    .left-image-block .image-caption {\r\n        right: 8px;\r\n        text-align: right;\r\n    }\r\n\r\n    .right-image-block .image-caption {\r\n        left: 8px;\r\n        text-align: left;\r\n    }\r\n\r\n    \/* Push right image to the right *\/\r\n    .right-image-block {\r\n        transform: translateX(100px);\r\n    }\r\n\r\n    @media (max-width: 767px) {\r\n\r\n        \/* Make images full width on mobile *\/\r\n        .center-image,\r\n        .left-image,\r\n        .right-image {\r\n            width: 100% !important;\r\n        }\r\n    }\r\n\r\n    \/* ===========================\r\n   STICKY TITLE\r\n   =========================== *\/\r\n    .sticky-xl-top {\r\n        top: 180px !important;\r\n        z-index: 0 !important;\r\n    }\r\n\r\n    \/* ===========================\r\n   BOTTOM CARDS\r\n   =========================== *\/\r\n\r\n    .card-icon-bottom {\r\n        width: 40px;\r\n        height: 40px;\r\n        flex: 0 0 40px;\r\n        \/* Evita que el icono se estire o encoja en flex *\/\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        \/* Centra el icono dentro del contenedor *\/\r\n    }\r\n\r\n    .card-icon-bottom img {\r\n        width: 100%;\r\n        height: 100%;\r\n        object-fit: contain;\r\n        \/* Mantiene la proporci\u00f3n del SVG *\/\r\n    }\r\n\r\n    \/* ===========================\r\n   VIDEO\r\n   =========================== *\/\r\n\r\n    .video-embed-container iframe {\r\n        width: 100%;\r\n        height: 100%;\r\n        border: none;\r\n        display: block;\r\n    }\r\n\r\n    .video-embed-container {\r\n        animation: fadeInVideo 0.3s ease;\r\n    }\r\n\r\n    @keyframes fadeInVideo {\r\n        from {\r\n            opacity: 0;\r\n            transform: scale(0.97);\r\n        }\r\n\r\n        to {\r\n            opacity: 1;\r\n            transform: scale(1);\r\n        }\r\n    }\r\n\r\n    .video-cover-trigger {\r\n        transform: translateZ(0);\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap {\r\n        position: absolute;\r\n        top: 50%;\r\n        left: 50%;\r\n        transform: translate(-50%, -50%) scale(1);\r\n        display: inline-block;\r\n        cursor: pointer;\r\n        transition: transform 0.25s ease;\r\n        backface-visibility: hidden;\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap:hover {\r\n        transform: translate(-50%, -50%) scale(1.1);\r\n    }\r\n\r\n    .video-cover-trigger .play-icon-wrap svg,\r\n    .video-cover-trigger .play-icon-wrap i {\r\n        pointer-events: none;\r\n        display: block;\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    \/\/ READ MORE MODULE\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const btn = document.getElementById('readmore-btn-e0481d1');\r\n        const content = document.getElementById('readmore-content-e0481d1');\r\n        \/\/ Solo si existen ambos elementos\r\n        if (btn && content) {\r\n            btn.addEventListener('click', function() {\r\n                const isVisible = content.classList.contains('d-block');\r\n                if (isVisible) {\r\n                    content.classList.remove('d-block');\r\n                    content.classList.add('d-none');\r\n                    btn.innerHTML = 'Leggi di pi\u00f9 <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-344 240-584l56-56 184 184 184-184 56 56-240 240Z\"\/><\/svg>';\r\n                    btn.classList.remove('mt-5');\r\n                } else {\r\n                    content.classList.remove('d-none');\r\n                    content.classList.add('d-block');\r\n                    btn.innerHTML = 'Leggi di meno <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#e3e3e3\"><path d=\"M480-528 296-344l-56-56 240-240 240 240-56 56-184-184Z\"\/><\/svg>';\r\n                    btn.classList.add('mt-5');\r\n                }\r\n            });\r\n        }\r\n    });\r\n\r\n    document.querySelectorAll('.video-cover-trigger').forEach(function(trigger) {\r\n        trigger.addEventListener('click', function() {\r\n            var videoId = this.dataset.videoId;\r\n            if (!videoId) return;\r\n\r\n            var wrapper = this.closest('.video-cover');\r\n            var container = wrapper.querySelector('.video-embed-container');\r\n\r\n            \/\/ Match iframe size to cover dimensions\r\n            var w = wrapper.offsetWidth;\r\n            var h = wrapper.offsetHeight;\r\n\r\n            \/\/ Size the wrapper explicitly so absolute children respect it\r\n            wrapper.style.width = w + 'px';\r\n            wrapper.style.height = h + 'px';\r\n\r\n            \/\/ Inject iframe with autoplay\r\n            container.innerHTML = '<iframe src=\"https:\/\/www.youtube.com\/embed\/' + videoId + '?autoplay=1&rel=0\" allowfullscreen allow=\"autoplay; encrypted-media\"><\/iframe>';\r\n\r\n            \/\/ Show iframe ON TOP of cover \u2014 do NOT hide the trigger\r\n            container.style.width = '100%';\r\n            container.style.height = '100%';\r\n            container.style.display = 'block';\r\n        });\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9de076b e-con-full e-flex e-con e-parent\" data-id=\"9de076b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfa76de elementor-widget elementor-widget-horizontal_slider_full_ellab\" data-id=\"cfa76de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"horizontal_slider_full_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-horizontal-slider-cfa76de\"\r\n    class=\"py-4 py-lg-5 px-3 px-md-0 section-horizontal-slider\"\r\n    aria-label=\"Graphs Carousel\">\r\n\r\n    <div class=\"container my-4 my-lg-5\">\r\n\r\n        <!-- Primera fila: t\u00edtulo y subtitulo -->\r\n        <div class=\"row mb-4\">\r\n            <div class=\"col-12 col-md-6 d-flex flex-column justify-content-end\">\r\n                                    <h2 class=\"fs-48 fw-semibold mb-5 text-primary\">\r\n                        <span class=\"text-primary\"><span class=\"text-secondary\">Opzioni di Apparecchiature<\/span> per Ogni Caso d'Uso<\/span>                    <\/h2>\r\n                            <\/div>\r\n\r\n            <div class=\"col-12 col-md-6 d-flex flex-column justify-content-end\">\r\n                                    <div class=\"fs-24 fw-semibold text-primary mb-5\">\r\n                        Sistemi wireless, cablati e ibridi, pronti per la spedizione, completamente calibrati e supportati da ValSuite\u00ae.                     <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n\r\n\r\n        <!-- Segunda fila: slider -->\r\n        <div class=\"row\">\r\n            <div class=\"col-12 col-md-12 overflow-visible pe-0\">\r\n                <div class=\"w-100\">\r\n                                            <div class=\"splide\" id=\"horizontal-slider-splide-cfa76de\">\r\n                            <div class=\"splide__track\">\r\n                                <ul class=\"splide__list d-flex\">\r\n                                                                                                                    <li class=\"splide__slide\" data-slide-image-position=\"default\">\r\n                                            <div class=\"bg-light rounded-2 d-flex flex-column align-items-start slide-content position-relative\">\r\n\r\n                                                <!-- BLOQUE 1: Texto -->\r\n                                                <div class=\"p-5 w-100\">\r\n                                                    <div class=\"fs-20 fw-semibold mb-4 text-start\">\r\n                                                        Data Logger Wireless per la Validazione                                                    <\/div>\r\n\r\n                                                    <div class=\"fs-18 fw-light text-start slide-text\">\r\n                                                        <p>Noleggia o prendi in leasing <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/datalogger-senza-fili\/\">logger wireless<\/a> e ottieni dati live affidabili. Con un'ampia gamma di opzioni di sensori e parametri, i nostri data logger TrackSense possono adattarsi a qualsiasi applicazione. <\/p>\n                                                    <\/div>\r\n\r\n                                                                                                    <\/div>\r\n\r\n                                                <!-- BLOQUE 2: Imagen -->\r\n                                                \r\n                                            <\/div>\r\n                                        <\/li>\r\n                                                                                                                    <li class=\"splide__slide\" data-slide-image-position=\"default\">\r\n                                            <div class=\"bg-light rounded-2 d-flex flex-column align-items-start slide-content position-relative\">\r\n\r\n                                                <!-- BLOQUE 1: Texto -->\r\n                                                <div class=\"p-5 w-100\">\r\n                                                    <div class=\"fs-20 fw-semibold mb-4 text-start\">\r\n                                                        Sistema di Validazione Cablato                                                    <\/div>\r\n\r\n                                                    <div class=\"fs-18 fw-light text-start slide-text\">\r\n                                                        <p>Ottieni un <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/sistema-di-convalida-cablato\/\">moderno sistema a termocoppia<\/a> per posizionamenti precisi e misurazioni di cui ti puoi fidare. Progettato per ambienti regolamentati, ottieni dati in tempo reale senza interruzioni. <\/p>\n                                                    <\/div>\r\n\r\n                                                                                                    <\/div>\r\n\r\n                                                <!-- BLOQUE 2: Imagen -->\r\n                                                \r\n                                            <\/div>\r\n                                        <\/li>\r\n                                                                                                                    <li class=\"splide__slide\" data-slide-image-position=\"default\">\r\n                                            <div class=\"bg-light rounded-2 d-flex flex-column align-items-start slide-content position-relative\">\r\n\r\n                                                <!-- BLOQUE 1: Texto -->\r\n                                                <div class=\"p-5 w-100\">\r\n                                                    <div class=\"fs-20 fw-semibold mb-4 text-start\">\r\n                                                        Data Logger Specializzati                                                    <\/div>\r\n\r\n                                                    <div class=\"fs-18 fw-light text-start slide-text\">\r\n                                                        <p>Noleggia o prendi in leasing qualsiasi prodotto dal nostro assortimento specializzato:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/datalogger-per-liofilizzazione\/\">Data logger per liofilizzazione e mappatura degli scaffali<\/a>.<\/li>\n<li><a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/datalogger-per-qualifica-di-congelatori\/\">Data logger per la qualificazione di congelatori a temperatura ultra-bassa<\/a>.<\/li>\n<li><a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/test-bowie-dick-elettronico\/\">Dispositivo elettronico per test Bowie Dick<\/a>.<\/li>\n<\/ul>\n                                                    <\/div>\r\n\r\n                                                                                                    <\/div>\r\n\r\n                                                <!-- BLOQUE 2: Imagen -->\r\n                                                \r\n                                            <\/div>\r\n                                        <\/li>\r\n                                                                                                                    <li class=\"splide__slide\" data-slide-image-position=\"default\">\r\n                                            <div class=\"bg-light rounded-2 d-flex flex-column align-items-start slide-content position-relative\">\r\n\r\n                                                <!-- BLOQUE 1: Texto -->\r\n                                                <div class=\"p-5 w-100\">\r\n                                                    <div class=\"fs-20 fw-semibold mb-4 text-start\">\r\n                                                        Software di validazione                                                    <\/div>\r\n\r\n                                                    <div class=\"fs-18 fw-light text-start slide-text\">\r\n                                                        <p>Incluso in tutti i noleggi e accordi di leasing c'\u00e8 il nostro <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/software-di-convalida\/\">software di validazione conforme, ValSuite\u00ae<\/a> - garantendoti i report riepilogativi di validazione di cui hai bisogno per il tuo prossimo audit. <\/p>\n                                                    <\/div>\r\n\r\n                                                                                                    <\/div>\r\n\r\n                                                <!-- BLOQUE 2: Imagen -->\r\n                                                \r\n                                            <\/div>\r\n                                        <\/li>\r\n                                                                                                                    <li class=\"splide__slide\" data-slide-image-position=\"default\">\r\n                                            <div class=\"bg-light rounded-2 d-flex flex-column align-items-start slide-content position-relative\">\r\n\r\n                                                <!-- BLOQUE 1: Texto -->\r\n                                                <div class=\"p-5 w-100\">\r\n                                                    <div class=\"fs-20 fw-semibold mb-4 text-start\">\r\n                                                        Raccordi e Accessori Specializzati                                                    <\/div>\r\n\r\n                                                    <div class=\"fs-18 fw-light text-start slide-text\">\r\n                                                        <p>A seconda delle tue applicazioni ed esigenze, offriamo un'ampia gamma di accessori e strumenti specializzati per garantire il corretto posizionamento dei sensori e il supporto ai processi.<\/p>\n                                                    <\/div>\r\n\r\n                                                                                                    <\/div>\r\n\r\n                                                <!-- BLOQUE 2: Imagen -->\r\n                                                \r\n                                            <\/div>\r\n                                        <\/li>\r\n                                                                    <\/ul>\r\n                            <\/div>\r\n                        <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n\r\n\r\n        <\/div>\r\n\r\n        <!-- Flechas abajo -->\r\n        <div class=\"horizontal-slider-arrows d-flex justify-content-end gap-3 mt-4 mb-md-0 mb-5\">\r\n            <button id=\"prev-cfa76de\">\u2039<\/button>\r\n            <button id=\"next-cfa76de\">\u203a<\/button>\r\n        <\/div>\r\n    <\/div>\r\n\r\n<\/section>\r\n\r\n\r\n\r\n\r\n\r\n<style>\r\n    #ellab-horizontal-slider-cfa76de {\r\n        background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-bg-img-9.png');\r\n        background-size: contain;\r\n        background-repeat: no-repeat;\r\n        background-position: bottom left;\r\n    }\r\n\r\n    @media (max-width: 991px) {\r\n        #ellab-horizontal-slider-cfa76de {\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    #horizontal-slider-splide-cfa76de  {\r\n        overflow: visible;\r\n        \/* importante para que se vea el siguiente slide *\/\r\n    }\r\n\r\n    #horizontal-slider-splide-cfa76de .splide__list {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        \/* alinea los slides al top *\/\r\n    }\r\n\r\n    \/* Desktop *\/\r\n    #horizontal-slider-splide-cfa76de .splide__slide {\r\n        display: flex;\r\n        flex-direction: column;\r\n        justify-content: flex-start;\r\n        flex: 0 0 auto;\r\n        width: auto;\r\n    }\r\n\r\n    \/* Mobile *\/\r\n    @media (max-width: 768px) {\r\n        #horizontal-slider-splide-cfa76de .splide__slide {\r\n            flex: 0 0 90%;\r\n        }\r\n    }\r\n\r\n    .horizontal-slider-arrows button {\r\n        width: 50px;\r\n        height: 50px;\r\n        padding: 0;\r\n        font-size: 2rem;\r\n        line-height: 1;\r\n        border-radius: 50%;\r\n        border: none;\r\n        background: var(--bs-light);\r\n        color: var(--bs-primary);\r\n        display: flex;\r\n        justify-content: center;\r\n        align-items: center;\r\n        transition: all 0.3s ease;\r\n        cursor: pointer;\r\n    }\r\n\r\n    \/* Hover activo *\/\r\n    .horizontal-slider-arrows button:hover {\r\n        background-color: var(--bs-primary);\r\n        color: #fff;\r\n        transform: scale(1.1);\r\n    }\r\n\r\n    \/* Estado inactivo *\/\r\n    .horizontal-slider-arrows button:disabled {\r\n        background-color: var(--bs-light);\r\n        color: var(--bs-primary);\r\n        cursor: default;\r\n    }\r\n\r\n    \/* Image Centered *\/\r\n    .slide-graph {\r\n        text-align: center;\r\n    }\r\n\r\n    \/* Image Bottom Position *\/\r\n    .slide-graph-bottom img {\r\n        display: block;\r\n        width: 100%;\r\n        height: auto;\r\n        object-fit: cover;\r\n    }\r\n\r\n    .slide-text ul {\r\n        list-style: disc;\r\n        padding-left: 1.2rem;\r\n        margin: 0;\r\n    }\r\n\r\n    .slide-text ul li {\r\n        display: list-item;\r\n        padding-left: 0.5rem;\r\n        margin-bottom: 1rem;\r\n    }\r\n<\/style>\r\n\r\n\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        if (typeof Splide !== 'undefined') {\r\n\r\n            var itemCount = 5;\r\n            var perPage = Math.min(4, itemCount);\r\n            var perPageTab = Math.min(2, itemCount);\r\n            var perPageMob = Math.min(1, itemCount);\r\n\r\n            var splide = new Splide('#horizontal-slider-splide-cfa76de', {\r\n                type: itemCount > perPage ? 'loop' : 'slide',\r\n                perPage: perPage,\r\n                autoplay: itemCount > perPage,\r\n                drag: itemCount > perPage,\r\n                arrows: false,\r\n\r\n                focus: 'left',\r\n                gap: '1rem',\r\n                pagination: false,\r\n                interval: 5000,\r\n                pauseOnHover: true,\r\n                trimSpace: false,\r\n                perMove: 1,\r\n                breakpoints: {\r\n                    1200: {\r\n                        perPage: perPageTab,\r\n                        drag: itemCount > perPageTab\r\n                    },\r\n                    992: {\r\n                        perPage: perPageMob,\r\n                        drag: itemCount > perPageTab\r\n                    },\r\n                    768: {\r\n                        perPage: 1,\r\n                        gap: '0.5rem'\r\n                    }\r\n                }\r\n            });\r\n\r\n            const prevBtn = document.getElementById('prev-cfa76de');\r\n            const nextBtn = document.getElementById('next-cfa76de');\r\n\r\n            prevBtn.addEventListener('click', () => splide.go('<'));\r\n            nextBtn.addEventListener('click', () => splide.go('>'));\r\n\r\n            function updateArrows() {\r\n                var width = window.innerWidth;\r\n                var currentPerPage;\r\n\r\n                if (width <= 768) {\r\n                    currentPerPage = 1;\r\n                } else if (width <= 992) {\r\n                    currentPerPage = perPageMob;\r\n                } else if (width <= 1200) {\r\n                    currentPerPage = perPageTab;\r\n                } else {\r\n                    currentPerPage = perPage;\r\n                }\r\n\r\n\r\n                console.log('width:', width);\r\n                console.log('itemCount:', itemCount);\r\n                console.log('currentPerPage:', currentPerPage);\r\n                console.log('needsSliding:', itemCount > currentPerPage);\r\n\r\n                var needsSliding = itemCount > currentPerPage;\r\n                prevBtn.style.display = needsSliding ? '' : 'none';\r\n                nextBtn.style.display = needsSliding ? '' : 'none';\r\n            }\r\n\r\n            \/\/ Ajusta altura de los slides\r\n            function setEqualSlideHeight() {\r\n                \/\/ Tomamos **todos los slides**, incluidos clones\r\n                const slides = document.querySelectorAll('#horizontal-slider-splide-cfa76de .splide__slide');\r\n                let maxHeight = 0;\r\n\r\n                \/\/ 1\ufe0f\u20e3 Encontrar la altura m\u00e1xima\r\n                slides.forEach(slide => {\r\n                    const content = slide.querySelector('.bg-light');\r\n                    if (content) {\r\n                        content.style.height = 'auto'; \/\/ reset\r\n                        const h = content.offsetHeight;\r\n                        if (h > maxHeight) maxHeight = h;\r\n                    }\r\n                });\r\n\r\n                \/\/ 2\ufe0f\u20e3 Asignar altura m\u00e1xima a todos los slides\r\n                slides.forEach(slide => {\r\n                    const content = slide.querySelector('.bg-light');\r\n                    if (content) {\r\n                        content.style.height = maxHeight + 'px';\r\n                    }\r\n                });\r\n            }\r\n\r\n            \/\/ Ejecutar al montar y al mover cada slide\r\n            splide.on('mounted', setEqualSlideHeight);\r\n            splide.on('move', setEqualSlideHeight);\r\n            window.addEventListener('resize', setEqualSlideHeight);\r\n\r\n\r\n            splide.mount();\r\n            updateArrows();\r\n        }\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c04fe0 e-con-full e-flex e-con e-parent\" data-id=\"8c04fe0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f32c934 elementor-widget elementor-widget-two_columns_with_grid_ellab\" data-id=\"f32c934\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"two_columns_with_grid_ellab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<section id=\"ellab-two-columns-with-grid-f32c934\" class=\"py-4 py-md-5 px-3 px-md-0 \">\r\n    <div class=\"container position-relative my-4 my-md-5\">\r\n\r\n                <!-- End Agenda Webinar -->\r\n\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n\r\n                                <div class=\"row d-flex align-items-end mb-5\">\r\n                                        <div class=\"col-12 col-12 col-md-6\">\r\n\r\n                                                    <h2 class=\"custom-title fs-48 fw-semibold mb-md-0 mb-5 text-primary\">\r\n                                <span class=\"text-primary\">Espandi le Tue <span class=\"text-secondary\">Capacit\u00e0 di Conformit\u00e0<\/span><\/span>                            <\/h2>\r\n                        \r\n                                            <\/div>\r\n\r\n                    \r\n                    <div class=\"col-12 col-12 col-md-6\">\r\n                        <!-- Title -->\r\n                        \r\n                        <!-- Counter -->\r\n                        \r\n                        <!-- Description -->\r\n                        \r\n                        <!-- Custom List -->\r\n                        \r\n                        <!-- Button Right -->\r\n                        \r\n                    <\/div>\r\n                <\/div>\r\n\r\n\r\n                \r\n\r\n\r\n                                    <div class=\"row g-4 align-items-stretch mb-5\">\r\n                                                    <div class=\"col-12 col-md-6 col-lg-4 d-flex mb-2 mb-md-5\">\r\n                                <div class=\"featured-item position-relative text-white rounded-4 overflow-hidden flex-grow-1\"\r\n                                    style=\"background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-grid-3.jpg'); background-size: cover; background-position: center;\">\r\n\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/datalogger-senza-fili\/\"\r\n                                            class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                                                                                                                    aria-hidden=\"true\" tabindex=\"-1\" style=\"z-index: 3;\">\r\n                                        <\/a>\r\n                                    \r\n                                    <!-- Gradient overlay -->\r\n                                                                        <!--<div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                            style=\"\">\r\n                                        <\/div>-->\r\n                                                                        <div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                        style=\"background: linear-gradient(to right, rgb(17 45 55 \/ 53%) 100%, rgba(var(--bs-primary-rgb), 0.55) 60%, transparent 100%); z-index: 1;\">\r\n                                    <\/div>\r\n                                    \r\n                                    <div class=\"p-4 p-md-5 d-flex flex-column h-100 justify-content-start position-relative\"\r\n                                        style=\"z-index: 2;\">\r\n\r\n                                        <h3 class=\"fs-20 fw-semibold my-3 text-white\">\r\n                                            Data logger wireless                                        <\/h3>\r\n\r\n                                                                                    <p class=\"fs-15 text-white mb-3\">\r\n                                                Registrazione di validazione wireless, flessibile e precisa.                                            <\/p>\r\n                                        \r\n                                                                                    <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/datalogger-senza-fili\/\"\r\n                                                class=\"text-white fw-semibold fs-15 position-relative\"\r\n                                                                                                >\r\n                                                Scopri di pi\u00f9                                            <\/a>\r\n                                        \r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12 col-md-6 col-lg-4 d-flex mb-2 mb-md-5\">\r\n                                <div class=\"featured-item position-relative text-white rounded-4 overflow-hidden flex-grow-1\"\r\n                                    style=\"background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-grid-1.jpg'); background-size: cover; background-position: center;\">\r\n\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/sistema-di-convalida-cablato\/\"\r\n                                            class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                                                                                                                    aria-hidden=\"true\" tabindex=\"-1\" style=\"z-index: 3;\">\r\n                                        <\/a>\r\n                                    \r\n                                    <!-- Gradient overlay -->\r\n                                                                        <!--<div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                            style=\"\">\r\n                                        <\/div>-->\r\n                                                                        <div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                        style=\"background: linear-gradient(to right, rgb(17 45 55 \/ 53%) 100%, rgba(var(--bs-primary-rgb), 0.55) 60%, transparent 100%); z-index: 1;\">\r\n                                    <\/div>\r\n                                    \r\n                                    <div class=\"p-4 p-md-5 d-flex flex-column h-100 justify-content-start position-relative\"\r\n                                        style=\"z-index: 2;\">\r\n\r\n                                        <h3 class=\"fs-20 fw-semibold my-3 text-white\">\r\n                                            Sistema di Validazione Cablato                                        <\/h3>\r\n\r\n                                                                                    <p class=\"fs-15 text-white mb-3\">\r\n                                                Configurazioni tradizionali a termocoppia per un controllo dettagliato della validazione.                                            <\/p>\r\n                                        \r\n                                                                                    <a href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/sistema-di-convalida-cablato\/\"\r\n                                                class=\"text-white fw-semibold fs-15 position-relative\"\r\n                                                                                                >\r\n                                                Scopri di pi\u00f9                                            <\/a>\r\n                                        \r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <div class=\"col-12 col-md-6 col-lg-4 d-flex mb-2 mb-md-5\">\r\n                                <div class=\"featured-item position-relative text-white rounded-4 overflow-hidden flex-grow-1\"\r\n                                    style=\"background-image: url('https:\/\/www.ellab.com\/wp-content\/uploads\/2025\/10\/wireless-grid-2.jpg'); background-size: cover; background-position: center;\">\r\n\r\n                                                                            <a href=\"https:\/\/www.ellab.com\/it\/convalida\/servizi-di-convalida\/\"\r\n                                            class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                                                                                                                    aria-hidden=\"true\" tabindex=\"-1\" style=\"z-index: 3;\">\r\n                                        <\/a>\r\n                                    \r\n                                    <!-- Gradient overlay -->\r\n                                                                        <!--<div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                            style=\"\">\r\n                                        <\/div>-->\r\n                                                                        <div class=\"position-absolute top-0 start-0 w-100 h-100\"\r\n                                        style=\"background: linear-gradient(to right, rgb(17 45 55 \/ 53%) 100%, rgba(var(--bs-primary-rgb), 0.55) 60%, transparent 100%); z-index: 1;\">\r\n                                    <\/div>\r\n                                    \r\n                                    <div class=\"p-4 p-md-5 d-flex flex-column h-100 justify-content-start position-relative\"\r\n                                        style=\"z-index: 2;\">\r\n\r\n                                        <h3 class=\"fs-20 fw-semibold my-3 text-white\">\r\n                                            Servizi di Validazione                                        <\/h3>\r\n\r\n                                                                                    <p class=\"fs-15 text-white mb-3\">\r\n                                                Esecuzione guidata da esperti e supporto per il successo normativo.                                            <\/p>\r\n                                        \r\n                                                                                    <a href=\"https:\/\/www.ellab.com\/it\/convalida\/servizi-di-convalida\/\"\r\n                                                class=\"text-white fw-semibold fs-15 position-relative\"\r\n                                                                                                >\r\n                                                Scopri di pi\u00f9                                            <\/a>\r\n                                        \r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                            <\/div>\r\n                \r\n                \r\n                \r\n                \r\n\r\n                \r\n\r\n\r\n                \r\n\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n\r\n\r\n<style>\r\n    #ellab-two-columns-with-grid-f32c934 {\r\n        background-image: url('');\r\n        background-repeat: no-repeat;\r\n        background-position: center center;\r\n        background-size: contain;\r\n            }\r\n\r\n    @media (max-width: 768px) {\r\n        #ellab-two-columns-with-grid-f32c934 {\r\n            background-position: center center;\r\n            background-image: none;\r\n        }\r\n    }\r\n\r\n    #ellab-two-columns-with-grid-f32c934 .container {\r\n        @media (min-width: 992px) {\r\n            min-height: vh;\r\n        }\r\n    }\r\n\r\n    .custom-list-wrapper .custom-dot {\r\n        width: 6px;\r\n        height: 6px;\r\n        background-color: #7BC70F;\r\n        \/* Cambia el color del punto *\/\r\n        border-radius: 50%;\r\n        margin-top: 8px;\r\n        \/* alinea con el t\u00edtulo *\/\r\n        flex-shrink: 0;\r\n    }\r\n\r\n    .agenda-col-time {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-col-topic {\r\n        flex: 0 0 60%;\r\n    }\r\n\r\n    .agenda-col-speaker {\r\n        flex: 0 0 20%;\r\n    }\r\n\r\n    .agenda-header,\r\n    .agenda-row {\r\n        display: flex;\r\n        align-items: center;\r\n    }\r\n\r\n    \/* LOGO GRID *\/\r\n\r\n    .logos-grid {\r\n        display: grid;\r\n        grid-template-columns: repeat(7, 1fr);\r\n        gap: 24px;\r\n        align-items: center;\r\n    }\r\n\r\n    .logo-item {\r\n        height: 100px;\r\n        \/* todos los logos ocupan la misma altura *\/\r\n        display: flex;\r\n        justify-content: center;\r\n        align-items: center;\r\n        padding: 10px;\r\n    }\r\n\r\n    .logo-item img {\r\n        max-width: 100%;\r\n        max-height: 100%;\r\n        width: auto;\r\n        height: auto;\r\n        object-fit: contain;\r\n    }\r\n\r\n    \/* Tablet *\/\r\n    @media (max-width:991px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(4, 1fr);\r\n        }\r\n    }\r\n\r\n    \/* Mobile *\/\r\n    @media (max-width:767px) {\r\n        .logos-grid {\r\n            grid-template-columns: repeat(3, 1fr);\r\n            gap: 12px;\r\n        }\r\n    }\r\n<\/style>\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        var countdownEl = document.getElementById('countdown-f32c934');\r\n        if (!countdownEl) return;\r\n\r\n        var endDate = new Date('1970-01-01 00:00:00').getTime();\r\n\r\n        function updateCountdown() {\r\n            var now = new Date().getTime();\r\n            var distance = endDate - now;\r\n            if (distance < 0) distance = 0;\r\n\r\n            var days = Math.floor(distance \/ (1000 * 60 * 60 * 24));\r\n            var hours = Math.floor((distance % (1000 * 60 * 60 * 24)) \/ (1000 * 60 * 60));\r\n            var minutes = Math.floor((distance % (1000 * 60 * 60)) \/ (1000 * 60));\r\n            var seconds = Math.floor((distance % (1000 * 60)) \/ 1000);\r\n\r\n            var values = [days, hours, minutes, seconds];\r\n\r\n            var spans = countdownEl.querySelectorAll('[data-count]');\r\n            spans.forEach(function(span, index) {\r\n                span.textContent = values[index].toString().padStart(2, '0');\r\n            });\r\n        }\r\n\r\n        updateCountdown();\r\n        setInterval(updateCountdown, 1000);\r\n    });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Noleggio e Leasing Flessibile di Data Logger Quando Ne Hai Bisogno Ottieni gli strumenti di validazione e il supporto di cui hai bisogno per rimanere conforme &#8211; alle tue condizioni Una soluzione intelligente per progetti di mappatura delle temperature e validazione, i servizi di leasing e noleggio di Ellab forniscono apparecchiature flessibili e pronte per [&hellip;]<\/p>\n","protected":false},"author":2456,"featured_media":0,"parent":17702,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/modules.php","meta":{"footnotes":""},"class_list":["post-18140","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Servizi di Noleggio Data Logger per la Validazione | Ellab<\/title>\n<meta name=\"description\" content=\"Scopri le nostre soluzioni di noleggio data logger per la validazione e la conformit\u00e0 nelle scienze della vita. Accesso immediato, nessuna preoccupazione per la manutenzione e flessibilit\u00e0 conveniente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noleggio e Leasing di Apparecchiature per la Validazione\" \/>\n<meta property=\"og:description\" content=\"Scopri le nostre soluzioni di noleggio data logger per la validazione e la conformit\u00e0 nelle scienze della vita. Accesso immediato, nessuna preoccupazione per la manutenzione e flessibilit\u00e0 conveniente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellab\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T10:57:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-isolator.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/noleggio-attrezzature-di-convalida\\\/\",\"url\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/noleggio-attrezzature-di-convalida\\\/\",\"name\":\"Servizi di Noleggio Data Logger per la Validazione | Ellab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/noleggio-attrezzature-di-convalida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/noleggio-attrezzature-di-convalida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ellab.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Module-application-isolator.png\",\"datePublished\":\"2026-02-23T11:28:29+00:00\",\"dateModified\":\"2026-05-22T10:57:05+00:00\",\"description\":\"Scopri le nostre soluzioni di noleggio data logger per la validazione e la conformit\u00e0 nelle scienze della vita. Accesso immediato, nessuna preoccupazione per la manutenzione e flessibilit\u00e0 conveniente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/noleggio-attrezzature-di-convalida\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/noleggio-attrezzature-di-convalida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/noleggio-attrezzature-di-convalida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ellab.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Module-application-isolator.png\",\"contentUrl\":\"https:\\\/\\\/www.ellab.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Module-application-isolator.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/noleggio-attrezzature-di-convalida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Validazione\",\"item\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sistemi di convalida\",\"item\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/convalida\\\/sistemi-di-convalida\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Noleggio e Leasing di Apparecchiature per la Validazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/\",\"name\":\"Ellab\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ellab.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Servizi di Noleggio Data Logger per la Validazione | Ellab","description":"Scopri le nostre soluzioni di noleggio data logger per la validazione e la conformit\u00e0 nelle scienze della vita. Accesso immediato, nessuna preoccupazione per la manutenzione e flessibilit\u00e0 conveniente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/","og_locale":"it_IT","og_type":"article","og_title":"Noleggio e Leasing di Apparecchiature per la Validazione","og_description":"Scopri le nostre soluzioni di noleggio data logger per la validazione e la conformit\u00e0 nelle scienze della vita. Accesso immediato, nessuna preoccupazione per la manutenzione e flessibilit\u00e0 conveniente.","og_url":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/","og_site_name":"Ellab","article_modified_time":"2026-05-22T10:57:05+00:00","og_image":[{"url":"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-isolator.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/","url":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/","name":"Servizi di Noleggio Data Logger per la Validazione | Ellab","isPartOf":{"@id":"https:\/\/www.ellab.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/#primaryimage"},"image":{"@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-isolator.png","datePublished":"2026-02-23T11:28:29+00:00","dateModified":"2026-05-22T10:57:05+00:00","description":"Scopri le nostre soluzioni di noleggio data logger per la validazione e la conformit\u00e0 nelle scienze della vita. Accesso immediato, nessuna preoccupazione per la manutenzione e flessibilit\u00e0 conveniente.","breadcrumb":{"@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/#primaryimage","url":"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-isolator.png","contentUrl":"https:\/\/www.ellab.com\/wp-content\/uploads\/2026\/03\/Module-application-isolator.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/noleggio-attrezzature-di-convalida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ellab.com\/it\/"},{"@type":"ListItem","position":2,"name":"Validazione","item":"https:\/\/www.ellab.com\/it\/convalida\/"},{"@type":"ListItem","position":3,"name":"Sistemi di convalida","item":"https:\/\/www.ellab.com\/it\/convalida\/sistemi-di-convalida\/"},{"@type":"ListItem","position":4,"name":"Noleggio e Leasing di Apparecchiature per la Validazione"}]},{"@type":"WebSite","@id":"https:\/\/www.ellab.com\/it\/#website","url":"https:\/\/www.ellab.com\/it\/","name":"Ellab","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ellab.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/18140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/users\/2456"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/comments?post=18140"}],"version-history":[{"count":2,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/18140\/revisions"}],"predecessor-version":[{"id":24090,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/18140\/revisions\/24090"}],"up":[{"embeddable":true,"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/pages\/17702"}],"wp:attachment":[{"href":"https:\/\/www.ellab.com\/it\/wp-json\/wp\/v2\/media?parent=18140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}